{"id":27092,"date":"2026-04-07T10:22:10","date_gmt":"2026-04-07T08:22:10","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-09-01#038;p=27071"},"modified":"2026-04-07T10:26:03","modified_gmt":"2026-04-07T08:26:03","slug":"living-museum-meeting-the-gardeners-2026-09-01","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/en\/begivenhed\/levende-museum-moed-gartnerne\/2026-09-01\/","title":{"rendered":"Living museum \u2013 Meet the gardeners"},"content":{"rendered":"<p>Living museum every Tuesday in the garden and in the Guldkorn exhibition.<\/p>\n<p>Every Tuesday you can meet the gardeners as they work in the Guldkorn exhibition and in the Polakhuset garden.<\/p>\n<p>Even though they are working and busy, they are always ready for a friendly approach and would like to contribute with their vast knowledge.<\/p>","protected":false},"excerpt":{"rendered":"<p>Living museum every Tuesday in the garden and in the Guldkorn exhibition. Every Tuesday you can meet the gardeners as they work in the Guldkorn exhibition and in the Polakhuset garden, respectively. Although they work\u2026<\/p>","protected":false},"author":17,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[48],"class_list":["post-27092","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-levende-museum","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/en\/event\/living-museum-meet-the-gardeners\/2026-09-01\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/en\/event\/living-museum-meet-the-gardeners\/2026-09-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T08:26:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-09-01\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-09-01\\\/\",\"name\":\"Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"datePublished\":\"2026-04-07T08:22:10+00:00\",\"dateModified\":\"2026-04-07T08:26:03+00:00\",\"description\":\"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-09-01\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-09-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-09-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Levende museum &#8211; M\u00f8d gartnerne\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-04-14\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Levende museum &#8211; M\u00f8d gartnerne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Living museum - Meet the gardeners - The Green Museum","description":"Every Tuesday you can meet the gardeners as they work in the Guldkorn exhibition and in the Polakhuset garden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/en\/event\/living-museum-meet-the-gardeners\/2026-09-01\/","og_locale":"en_GB","og_type":"article","og_title":"Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum","og_description":"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.","og_url":"https:\/\/detgroennemuseum.dk\/en\/event\/living-museum-meet-the-gardeners\/2026-09-01\/","og_site_name":"Det Gr\u00f8nne Museum","article_modified_time":"2026-04-07T08:26:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-09-01\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-09-01\/","name":"Living museum - Meet the gardeners - The Green Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"datePublished":"2026-04-07T08:22:10+00:00","dateModified":"2026-04-07T08:26:03+00:00","description":"Every Tuesday you can meet the gardeners as they work in the Guldkorn exhibition and in the Polakhuset garden.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-09-01\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-09-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-09-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"Levende museum &#8211; M\u00f8d gartnerne","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-04-14\/"},{"@type":"ListItem","position":4,"name":"Levende museum &#8211; M\u00f8d gartnerne"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"The Green Museum","description":"Denmark&#039;s National Museum of Hunting, Forestry, Agriculture and Food","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events\/27092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events\/27092\/revisions"}],"predecessor-version":[{"id":27125,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events\/27092\/revisions\/27125"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/media?parent=27092"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tags?post=27092"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=27092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}