{"id":10002140,"date":"2024-12-02T12:55:55","date_gmt":"2024-12-02T11:55:55","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;p=24737"},"modified":"2024-12-02T12:55:55","modified_gmt":"2024-12-02T11:55:55","slug":"decorate-your-own-gingerbread-heart","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/en\/begivenhed\/dekorer-dit-eget-honningkagehjerte\/2024-12-07\/","title":{"rendered":"Decorate your own gingerbread heart"},"content":{"rendered":"<p><strong>Decorate your own gingerbread heart<\/strong><\/p>\n<p>Come and unleash your creativity in our cozy gingerbread workshop! Every Advent weekend you can decorate your own honey heart with icing and take it home \u2013 or maybe give it as a sweet gift.<\/p>\n<p>Time: Advent weekends (Saturday and Sunday) from 10 am to 4 pm<br \/>\nPrice: Only 15 DKK per heart (when entrance fee is paid)<\/p>\n<p>Bring the family and let the Christmas spirit spread!<\/p>\n<p><strong>Also experience our Christmas exhibition \u2013 Christmas of All Time.<\/strong><br class=\"html-br\" \/>Step into the history of Christmas and get into the Christmas spirit with All Time Christmas at Det Gr\u00f8nne Museum! From now until December 29th, you can travel through 300 years of Christmas traditions, meet the animals in the stable and visit the winter garden, where the roots of Christmas traditions unfold. Perfect for the whole family!<\/p>\n<p><a href=\"https:\/\/detgroennemuseum.dk\/en\/christmas\/\">Read more here.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Decorate your own gingerbread heart Come and unleash your creativity in our cozy gingerbread workshop! Every Advent weekend you can decorate your own honey heart with icing and take it home \u2013 or\u2026<\/p>","protected":false},"author":17,"featured_media":24738,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[44],"class_list":["post-10002140","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-ferieaktiviteter","cat_ferieaktiviteter","tribe-recurring-event","tribe-recurring-event-parent","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dekorer dit eget honningkagehjerte - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Kom og slip kreativiteten l\u00f8s i vores hyggelige honningkagev\u00e6rksted! Hver adventsweekend kan du pynte dit eget honninghjerte med glasur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/en\/event\/decorate-your-own-gingerbread-heart\/2024-12-07\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dekorer dit eget honningkagehjerte - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Kom og slip kreativiteten l\u00f8s i vores hyggelige honningkagev\u00e6rksted! Hver adventsweekend kan du pynte dit eget honninghjerte med glasur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/en\/event\/decorate-your-own-gingerbread-heart\/2024-12-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/julemarked-foerste-dag-1500px-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/\",\"name\":\"Dekorer dit eget honningkagehjerte - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/julemarked-foerste-dag-1500px-13.jpg\",\"datePublished\":\"2024-12-02T11:55:55+00:00\",\"description\":\"Kom og slip kreativiteten l\u00f8s i vores hyggelige honningkagev\u00e6rksted! Hver adventsweekend kan du pynte dit eget honninghjerte med glasur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/julemarked-foerste-dag-1500px-13.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/julemarked-foerste-dag-1500px-13.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Der dekoreres honningkagehjerte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/de\\\/ereignis\\\/verzieren-sie-ihr-eigenes-lebkuchenherz\\\/2024-12-07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dekorer dit eget honningkagehjerte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decorate your own gingerbread heart - The Green Museum","description":"Come and unleash your creativity in our cozy gingerbread workshop! Every Advent weekend you can decorate your own honey heart with icing.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/en\/event\/decorate-your-own-gingerbread-heart\/2024-12-07\/","og_locale":"en_GB","og_type":"article","og_title":"Dekorer dit eget honningkagehjerte - Det Gr\u00f8nne Museum","og_description":"Kom og slip kreativiteten l\u00f8s i vores hyggelige honningkagev\u00e6rksted! Hver adventsweekend kan du pynte dit eget honninghjerte med glasur.","og_url":"https:\/\/detgroennemuseum.dk\/en\/event\/decorate-your-own-gingerbread-heart\/2024-12-07\/","og_site_name":"Det Gr\u00f8nne Museum","og_image":[{"width":1500,"height":1000,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/julemarked-foerste-dag-1500px-13.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/","url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/","name":"Decorate your own gingerbread heart - The Green Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/julemarked-foerste-dag-1500px-13.jpg","datePublished":"2024-12-02T11:55:55+00:00","description":"Come and unleash your creativity in our cozy gingerbread workshop! Every Advent weekend you can decorate your own honey heart with icing.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/julemarked-foerste-dag-1500px-13.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/julemarked-foerste-dag-1500px-13.jpg","width":1500,"height":1000,"caption":"Der dekoreres honningkagehjerte"},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/verzieren-sie-ihr-eigenes-lebkuchenherz\/2024-12-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"Dekorer dit eget honningkagehjerte"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"The Green Museum","description":"Denmark&#039;s National Museum of Hunting, Forestry, Agriculture and Food","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events\/10002140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":0,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events\/10002140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/media\/24738"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/media?parent=10002140"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tags?post=10002140"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10002140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}