{"id":27281,"date":"2026-04-07T11:03:33","date_gmt":"2026-04-07T09:03:33","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-07-23#038;p=27269"},"modified":"2026-06-25T08:13:50","modified_gmt":"2026-06-25T06:13:50","slug":"treffen-sie-die-freiwilligenvereinigung-fur-manner-und-frauen-am-23-juli-2026","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-07-23\/","title":{"rendered":"Lernen Sie die Freiwilligen kennen: Karle- und Pigelauget"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Das ganze Jahr \u00fcber arbeitet die M\u00e4nner- und Frauengilde des Museums auf den historischen Feldern.<\/p>\n<p>Kommen Sie und erleben Sie ihre Arbeit. Wenn Sie Gl\u00fcck haben, k\u00f6nnen Sie sogar ein paar frische, frisch geerntete Kartoffeln mit nach Hause nehmen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Das diesj\u00e4hrige Programm.<\/strong><\/p>\n<p>Donnerstag, 9. April, 12:00-15:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang auf den historischen Feldern \u2013 Kartoffel- und R\u00fcbenanbau.<\/p>\n<p>Donnerstag, 7. Mai, 12:00-15:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 R\u00fcbenpfl\u00fccken<\/p>\n<p>Donnerstag, 4. Juni, 12:00-15:00 Uhr \u2013 Die diesj\u00e4hrige Wanderung am De Historiske Marker \u2013 R\u00fcbenpfl\u00fccken<\/p>\n<p><span style=\"color: #ff0000;\">ABGESAGT Donnerstag, 25. Juni, 12:00-15:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 R\u00fcbenpfl\u00fccken<\/span><\/p>\n<p>Donnerstag, 2. Juli, 12:00-15:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Ernten von Fr\u00fchkartoffeln und Schneiden von R\u00fcben<\/p>\n<p>Donnerstag, 9. Juli, 12:00\u201315:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Ernten von Fr\u00fchkartoffeln und Schneiden von R\u00fcben<\/p>\n<p>Donnerstag, 16. Juli, 12:00\u201315:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Ernten von Fr\u00fchkartoffeln und Schneiden von R\u00fcben<\/p>\n<p>Donnerstag, 23. Juli, 12:00\u201315:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Fr\u00fchkartoffeln ernten und R\u00fcben schneiden<\/p>\n<p>Donnerstag, 30. Juli, 12:00\u201315:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Fr\u00fchkartoffeln ernten und R\u00fcben schneiden<\/p>\n<p>Samstag, 8. August, 12:00\u201315:00 Uhr \u2013 Der Jahresrundgang auf den historischen Feldern \u2013 Ernten mit Selbstbindern<\/p>\n<p>Samstag, 15. August, 12:00-15:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Ernte mit einem M\u00e4hdrescher<\/p>\n<p>Donnerstag, 1. Oktober, 12:00-15:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 Ernten von sp\u00e4ten Kartoffeln<\/p>\n<p>Donnerstag, 15. Oktober, 12:00\u201315:00 Uhr \u2013 Der diesj\u00e4hrige Spaziergang durch die historischen Felder \u2013 R\u00fcbenpfl\u00fccken<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das ganze Jahr \u00fcber arbeitet der Museumsbesitzer Karle- und Pigelaug auf den historischen Feldern. Kommen Sie vorbei und erleben Sie die Arbeit. Mit etwas Gl\u00fcck k\u00f6nnen Sie sogar\u2026<\/p>","protected":false},"author":17,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[168,48],"class_list":["post-27281","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-aarets-gang","tribe_events_cat-levende-museum","cat_aarets-gang","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f8d de frivillige: Karle- og Pigelauget - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-gilde-der-manner-und-frauen-kennen-3\/2026-07-23\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f8d de frivillige: Karle- og Pigelauget - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-gilde-der-manner-und-frauen-kennen-3\/2026-07-23\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T06:13:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-karle-og-pigelauget-3\\\/2026-07-23\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-karle-og-pigelauget-3\\\/2026-07-23\\\/\",\"name\":\"M\u00f8d de frivillige: Karle- og Pigelauget - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"datePublished\":\"2026-04-07T09:03:33+00:00\",\"dateModified\":\"2026-06-25T06:13:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-karle-og-pigelauget-3\\\/2026-07-23\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-karle-og-pigelauget-3\\\/2026-07-23\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-karle-og-pigelauget-3\\\/2026-07-23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00f8d de frivillige: Karle- og Pigelauget\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-karle-og-pigelauget-3\\\/2026-04-09\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00f8d de frivillige: Karle- og Pigelauget\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Treffen Sie die Freiwilligen: Karle- og Pigelauget \u2013 Das Gr\u00fcne Museum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-gilde-der-manner-und-frauen-kennen-3\/2026-07-23\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00f8d de frivillige: Karle- og Pigelauget - Det Gr\u00f8nne Museum","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-gilde-der-manner-und-frauen-kennen-3\/2026-07-23\/","og_site_name":"Det Gr\u00f8nne Museum","article_modified_time":"2026-06-25T06:13:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-07-23\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-07-23\/","name":"Treffen Sie die Freiwilligen: Karle- og Pigelauget \u2013 Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"datePublished":"2026-04-07T09:03:33+00:00","dateModified":"2026-06-25T06:13:50+00:00","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-07-23\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-07-23\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-07-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"M\u00f8d de frivillige: Karle- og Pigelauget","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-karle-og-pigelauget-3\/2026-04-09\/"},{"@type":"ListItem","position":4,"name":"M\u00f8d de frivillige: Karle- og Pigelauget"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":4,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27281\/revisions"}],"predecessor-version":[{"id":27887,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27281\/revisions\/27887"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=27281"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=27281"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=27281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}