{"id":27170,"date":"2026-04-07T10:32:06","date_gmt":"2026-04-07T08:32:06","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-07-08#038;p=27070"},"modified":"2026-04-07T10:32:06","modified_gmt":"2026-04-07T08:32:06","slug":"treffen-sie-die-freiwilligen-schmiede-2-2026-07-08","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/moed-de-frivillige-smedene-2\/2026-07-08\/","title":{"rendered":"Lernen Sie die Freiwilligen kennen: Die Smiths"},"content":{"rendered":"<p>Treffen Sie die Freiwilligen in der alten Schmiede des Gr\u00fcnen Museums, w\u00e4hrend sie an der Schmiede arbeiten und Eisen mit Feuer, Hammer und Amboss z\u00e4hmen, wie es die Menschen seit pr\u00e4historischen Zeiten tun und wie es schon seit langem in Gammel Estrup getan wird.<\/p>\n<p>Die Schmiede wurde 1761 als Teil des gro\u00dfen Komplexes landwirtschaftlicher Geb\u00e4ude errichtet, der in Gl. errichtet wurde. Estrup im 17. und 18. Jahrhundert. Die Schmiede befindet sich am \u00e4u\u00dfersten Rand der Zuchtgeb\u00e4ude, wo die M\u00f6glichkeit, die Ausbreitung eines m\u00f6glichen Feuers zu verhindern, am gr\u00f6\u00dften ist.<\/p>\n<p>In der alten, traditionellen Schmiede zeigt das Gr\u00fcne Museum Smedelaug die historische Handwerkskunst mit Feuer in der Axt und dem H\u00e4mmern des Hammers gegen den Amboss, w\u00e4hrend Erfahrungen und Geschichten aus dem Leben als Schmiede ausgelassen werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Treffen Sie die Freiwilligen in der alten Schmiede des Gr\u00fcnen Museums, w\u00e4hrend sie an der Schmiede arbeiten und Eisen mit Feuer, Hammer und Amboss z\u00e4hmen, wie es die Menschen seit pr\u00e4historischen Zeiten tun \u2026<\/p>","protected":false},"author":17,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[48],"class_list":["post-27170","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-levende-museum","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f8d de frivillige: Smedene - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"M\u00f8d de frivillige smede p\u00e5 Det Gr\u00f8nne Museum, n\u00e5r de arbejder ved essen og t\u00e6mmer jern ved hj\u00e6lp af ild, hammer og ambolt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-schmiede-2\/2026-07-08\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f8d de frivillige: Smedene - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"M\u00f8d de frivillige smede p\u00e5 Det Gr\u00f8nne Museum, n\u00e5r de arbejder ved essen og t\u00e6mmer jern ved hj\u00e6lp af ild, hammer og ambolt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-schmiede-2\/2026-07-08\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-smedene-2\\\/2026-07-08\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-smedene-2\\\/2026-07-08\\\/\",\"name\":\"M\u00f8d de frivillige: Smedene - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"datePublished\":\"2026-04-07T08:32:06+00:00\",\"description\":\"M\u00f8d de frivillige smede p\u00e5 Det Gr\u00f8nne Museum, n\u00e5r de arbejder ved essen og t\u00e6mmer jern ved hj\u00e6lp af ild, hammer og ambolt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-smedene-2\\\/2026-07-08\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-smedene-2\\\/2026-07-08\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-smedene-2\\\/2026-07-08\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00f8d de frivillige: Smedene\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-smedene-2\\\/2026-06-02\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00f8d de frivillige: Smedene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Treffen Sie die Freiwilligen: Die Schmiede - Das Gr\u00fcne Museum","description":"Treffen Sie die freiwilligen Schmiede im Green Museum bei ihrer Arbeit an der Esse und beim Formen von Eisen mit Feuer, Hammer und Amboss.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-schmiede-2\/2026-07-08\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00f8d de frivillige: Smedene - Det Gr\u00f8nne Museum","og_description":"M\u00f8d de frivillige smede p\u00e5 Det Gr\u00f8nne Museum, n\u00e5r de arbejder ved essen og t\u00e6mmer jern ved hj\u00e6lp af ild, hammer og ambolt.","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-schmiede-2\/2026-07-08\/","og_site_name":"Det Gr\u00f8nne Museum","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-smedene-2\/2026-07-08\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-smedene-2\/2026-07-08\/","name":"Treffen Sie die Freiwilligen: Die Schmiede - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"datePublished":"2026-04-07T08:32:06+00:00","description":"Treffen Sie die freiwilligen Schmiede im Green Museum bei ihrer Arbeit an der Esse und beim Formen von Eisen mit Feuer, Hammer und Amboss.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-smedene-2\/2026-07-08\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-smedene-2\/2026-07-08\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-smedene-2\/2026-07-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"M\u00f8d de frivillige: Smedene","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-smedene-2\/2026-06-02\/"},{"@type":"ListItem","position":4,"name":"M\u00f8d de frivillige: Smedene"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":0,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27170\/revisions"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=27170"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=27170"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=27170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}