{"id":27091,"date":"2026-04-07T10:22:10","date_gmt":"2026-04-07T08:22:10","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-08-25#038;p=27071"},"modified":"2026-04-07T10:26:03","modified_gmt":"2026-04-07T08:26:03","slug":"lebendiges-museum-trifft-die-gartner-25-08-2026","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/levende-museum-moed-gartnerne\/2026-08-25\/","title":{"rendered":"Lebendiges Museum \u2013 Treffen Sie die G\u00e4rtner"},"content":{"rendered":"<p>Jeden Dienstag Lebendiges Museum im Garten und in der Guldkorn-Ausstellung.<\/p>\n<p>Jeden Dienstag k\u00f6nnen Sie den G\u00e4rtnern bei ihrer Arbeit in der Guldkorn-Ausstellung und im Polakhuset-Garten zusehen.<\/p>\n<p>Obwohl sie berufst\u00e4tig und besch\u00e4ftigt sind, sind sie immer f\u00fcr eine freundliche Ansprache bereit und m\u00f6chten ihr umfangreiches Wissen einbringen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jeden Dienstag Lebendiges Museum im Garten und in der Guldkorn-Ausstellung. Jeden Dienstag k\u00f6nnen Sie den G\u00e4rtnern bei ihrer Arbeit in der Guldkorn-Ausstellung und im Polakhuset-Garten zusehen. Auch wenn sie funktionieren \u2026<\/p>","protected":false},"author":17,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[48],"class_list":["post-27091","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-levende-museum","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lebendes-museum-treffen-sie-die-gartner\/2026-08-25\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lebendes-museum-treffen-sie-die-gartner\/2026-08-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T08:26:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-08-25\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-08-25\\\/\",\"name\":\"Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"datePublished\":\"2026-04-07T08:22:10+00:00\",\"dateModified\":\"2026-04-07T08:26:03+00:00\",\"description\":\"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-08-25\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-08-25\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-08-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Levende museum &#8211; M\u00f8d gartnerne\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/levende-museum-moed-gartnerne\\\/2026-04-14\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Levende museum &#8211; M\u00f8d gartnerne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lebendiges Museum - Treffen Sie die G\u00e4rtner - Das Gr\u00fcne Museum","description":"Jeden Dienstag k\u00f6nnen Sie den G\u00e4rtnern bei ihrer Arbeit in der Guldkorn-Ausstellung und im Polakhuset-Garten zusehen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lebendes-museum-treffen-sie-die-gartner\/2026-08-25\/","og_locale":"de_DE","og_type":"article","og_title":"Levende museum - M\u00f8d gartnerne - Det Gr\u00f8nne Museum","og_description":"Hver tirsdag kan du m\u00f8de gartnerne, n\u00e5r de arbejder i henholdsvis udstillingen Guldkorn og i Polakhusets have.","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lebendes-museum-treffen-sie-die-gartner\/2026-08-25\/","og_site_name":"Det Gr\u00f8nne Museum","article_modified_time":"2026-04-07T08:26:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-08-25\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-08-25\/","name":"Lebendiges Museum - Treffen Sie die G\u00e4rtner - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"datePublished":"2026-04-07T08:22:10+00:00","dateModified":"2026-04-07T08:26:03+00:00","description":"Jeden Dienstag k\u00f6nnen Sie den G\u00e4rtnern bei ihrer Arbeit in der Guldkorn-Ausstellung und im Polakhuset-Garten zusehen.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-08-25\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-08-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-08-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"Levende museum &#8211; M\u00f8d gartnerne","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/levende-museum-moed-gartnerne\/2026-04-14\/"},{"@type":"ListItem","position":4,"name":"Levende museum &#8211; M\u00f8d gartnerne"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27091\/revisions"}],"predecessor-version":[{"id":27124,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27091\/revisions\/27124"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=27091"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=27091"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=27091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}