{"id":27030,"date":"2026-04-07T10:16:03","date_gmt":"2026-04-07T08:16:03","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-10-28#038;p=27000"},"modified":"2026-04-07T10:17:15","modified_gmt":"2026-04-07T08:17:15","slug":"treffen-sie-die-freiwilligen-in-der-traktorwerkstatt-am-28-10-2026","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/","title":{"rendered":"Treffen Sie die Freiwilligen in der Traktorwerkstatt"},"content":{"rendered":"<p><strong>LEBENDES MUSEUM \/ Regelm\u00e4\u00dfige Veranstaltung \/ Kostenlos bei bezahltem Eintritt<\/strong><\/p>\n<p>Treffen Sie die Freiwilligen in der Traktorwerkstatt, wo sie an vielen verschiedenen Aufgaben arbeiten. So kommen die Maschinen beispielsweise zur Inspektion und Reparatur in die Traktorenwerkstatt, bevor sie von den ehrenamtlichen Mitarbeitern des Museums bei ihrer Arbeit auf den Historischen Feldern eingesetzt werden.<\/p>\n<p>In der Traktorenwerkstatt herrscht immer reges Treiben, es herrscht Ger\u00e4uschkulisse und es gibt teilmontierte Maschinen und Motoren. Die Ehrenamtlichen beantworten gerne Fragen, erkl\u00e4ren ihre Arbeit und erz\u00e4hlen Geschichten aus einem langen Arbeitsleben mit gro\u00dfen Maschinen \u2013 z. B.: wie Schmiede.<\/p>","protected":false},"excerpt":{"rendered":"<p>LEBENDES MUSEUM \/ Wiederkehrende Veranstaltung \/ Kostenlos bei bezahltem Eintritt. Treffen Sie die Freiwilligen in der Traktorwerkstatt, wo sie viele verschiedene Aufgaben erledigen. Beispielsweise kommen die Maschinen zur Inspektion und\u2026<\/p>","protected":false},"author":17,"featured_media":9559,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[48],"class_list":["post-27030","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-levende-museum","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f8d de frivillige i Traktor-v\u00e6rkstedet - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"M\u00f8d de frivillige i traktorv\u00e6rkstedet. Her har de altid gang i at efterse eller renovere en af vores veteranmaskiner.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-in-der-traktorenwerkstatt\/2026-10-28\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"M\u00f8d de frivillige i traktorv\u00e6rkstedet. Her har de altid gang i at efterse eller renovere en af vores veteranmaskiner.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-in-der-traktorenwerkstatt\/2026-10-28\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T08:17:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2019\/09\/traktorvaerkstedet-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/\",\"name\":\"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/traktorvaerkstedet-3.jpg\",\"datePublished\":\"2026-04-07T08:16:03+00:00\",\"dateModified\":\"2026-04-07T08:17:15+00:00\",\"description\":\"M\u00f8d de frivillige i traktorv\u00e6rkstedet. Her har de altid gang i at efterse eller renovere en af vores veteranmaskiner.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/traktorvaerkstedet-3.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/traktorvaerkstedet-3.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"M\u00f8d de frivillige i Det Gr\u00f8nne Museums Traktorv\u00e6rksted p\u00e5 Gammel Estrup\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-10-28\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-i-traktor-vaerkstedet\\\/2026-04-08\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Treffen Sie die Freiwilligen in der Traktorwerkstatt - Das Gr\u00fcne Museum","description":"Treffen Sie die Freiwilligen in der Traktorwerkstatt. Hier sind sie immer damit besch\u00e4ftigt, eine unserer Oldtimermaschinen zu inspizieren oder zu renovieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-in-der-traktorenwerkstatt\/2026-10-28\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet - Det Gr\u00f8nne Museum","og_description":"M\u00f8d de frivillige i traktorv\u00e6rkstedet. Her har de altid gang i at efterse eller renovere en af vores veteranmaskiner.","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-in-der-traktorenwerkstatt\/2026-10-28\/","og_site_name":"Det Gr\u00f8nne Museum","article_modified_time":"2026-04-07T08:17:15+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2019\/09\/traktorvaerkstedet-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/","name":"Treffen Sie die Freiwilligen in der Traktorwerkstatt - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2019\/09\/traktorvaerkstedet-3.jpg","datePublished":"2026-04-07T08:16:03+00:00","dateModified":"2026-04-07T08:17:15+00:00","description":"Treffen Sie die Freiwilligen in der Traktorwerkstatt. Hier sind sie immer damit besch\u00e4ftigt, eine unserer Oldtimermaschinen zu inspizieren oder zu renovieren.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2019\/09\/traktorvaerkstedet-3.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2019\/09\/traktorvaerkstedet-3.jpg","width":1920,"height":1280,"caption":"M\u00f8d de frivillige i Det Gr\u00f8nne Museums Traktorv\u00e6rksted p\u00e5 Gammel Estrup"},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-10-28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-i-traktor-vaerkstedet\/2026-04-08\/"},{"@type":"ListItem","position":4,"name":"M\u00f8d de frivillige i Traktor-v\u00e6rkstedet"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27030\/revisions"}],"predecessor-version":[{"id":27064,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/27030\/revisions\/27064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/9559"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=27030"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=27030"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=27030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}