{"id":26974,"date":"2026-04-07T10:01:59","date_gmt":"2026-04-07T08:01:59","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-07-30#038;p=26938"},"modified":"2026-04-07T10:01:59","modified_gmt":"2026-04-07T08:01:59","slug":"treffen-sie-die-freiwilligen-am-30-07-2026","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/moed-de-frivillige\/2026-07-30\/","title":{"rendered":"Treffen Sie die Freiwilligen: Die Gastwirte"},"content":{"rendered":"<p>Treffen Sie die Tour-Betreuer, die Ihnen von den gro\u00dfen land- und forstwirtschaftlichen Maschinen, Karren und Werkzeugen erz\u00e4hlen, die in Reihen im Besuchermagazin des Museums stehen.<\/p>\n<p>Das Besucherzentrum des Gr\u00fcnen Museums befindet sich in zwei von Gl. Estrups Zuchtgeb\u00e4ude: das Reithaus und der Agerumsladen. Hier ist ein ausgew\u00e4hlter Teil der gro\u00dfen Sammlungen des Gr\u00fcnen Museums, Wagenrad f\u00fcr Wagenrad und Vogelfl\u00fcgel f\u00fcr Vogelfl\u00fcgel, unterteilt in die Themen: Wagen und Kutschen, Traktoren und Maschinen, Jagd und Natur sowie Forst- und Landmaschinen.<\/p>\n<p>Die Besucherbetreuer des Gr\u00fcnen Museums beantworten gerne Fragen, erkl\u00e4ren die Maschinen und erz\u00e4hlen Geschichten aus ihrem eigenen Leben mit den gro\u00dfen Maschinen, z. B.: als Landwirte.<\/p>","protected":false},"excerpt":{"rendered":"<p>Treffen Sie die Tour-Betreuer, die Ihnen von den gro\u00dfen land- und forstwirtschaftlichen Maschinen, Karren und Werkzeugen erz\u00e4hlen, die in Reihen im Besuchermagazin des Museums stehen. Das Besucherzentrum des Gr\u00fcnen Museums befindet sich in zwei\u2026<\/p>","protected":false},"author":17,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[48],"class_list":["post-26974","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-levende-museum","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"M\u00f8d bes\u00f8gsv\u00e6rterne som fort\u00e6ller om land- og skovbrugets store maskiner, vogne og redskaber, der st\u00e5r p\u00e5 rad og r\u00e6kke i museets Bes\u00f8gsmagasin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-kennen\/2026-07-30\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"M\u00f8d bes\u00f8gsv\u00e6rterne som fort\u00e6ller om land- og skovbrugets store maskiner, vogne og redskaber, der st\u00e5r p\u00e5 rad og r\u00e6kke i museets Bes\u00f8gsmagasin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-kennen\/2026-07-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige\\\/2026-07-30\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige\\\/2026-07-30\\\/\",\"name\":\"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"datePublished\":\"2026-04-07T08:01:59+00:00\",\"description\":\"M\u00f8d bes\u00f8gsv\u00e6rterne som fort\u00e6ller om land- og skovbrugets store maskiner, vogne og redskaber, der st\u00e5r p\u00e5 rad og r\u00e6kke i museets Bes\u00f8gsmagasin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige\\\/2026-07-30\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige\\\/2026-07-30\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige\\\/2026-07-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige\\\/2026-05-06\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Treffen Sie die Freiwilligen: Die Besucherbetreuer - Das Gr\u00fcne Museum","description":"Treffen Sie die Tour-Betreuer, die Ihnen von den gro\u00dfen land- und forstwirtschaftlichen Maschinen, Karren und Werkzeugen erz\u00e4hlen, die in Reihen im Besuchermagazin des Museums stehen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-kennen\/2026-07-30\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne - Det Gr\u00f8nne Museum","og_description":"M\u00f8d bes\u00f8gsv\u00e6rterne som fort\u00e6ller om land- og skovbrugets store maskiner, vogne og redskaber, der st\u00e5r p\u00e5 rad og r\u00e6kke i museets Bes\u00f8gsmagasin.","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/lernen-sie-die-freiwilligen-kennen\/2026-07-30\/","og_site_name":"Det Gr\u00f8nne Museum","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige\/2026-07-30\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige\/2026-07-30\/","name":"Treffen Sie die Freiwilligen: Die Besucherbetreuer - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"datePublished":"2026-04-07T08:01:59+00:00","description":"Treffen Sie die Tour-Betreuer, die Ihnen von den gro\u00dfen land- und forstwirtschaftlichen Maschinen, Karren und Werkzeugen erz\u00e4hlen, die in Reihen im Besuchermagazin des Museums stehen.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige\/2026-07-30\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige\/2026-07-30\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige\/2026-07-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige\/2026-05-06\/"},{"@type":"ListItem","position":4,"name":"M\u00f8d de frivillige: Bes\u00f8gsv\u00e6rterne"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/26974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":0,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/26974\/revisions"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=26974"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=26974"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=26974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}