{"id":26925,"date":"2026-04-07T08:38:32","date_gmt":"2026-04-07T06:38:32","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;eventDate=2026-09-29#038;p=26900"},"modified":"2026-04-10T11:42:21","modified_gmt":"2026-04-10T09:42:21","slug":"treffen-sie-die-freiwilligen-der-lebensmittelgilde-2026-09-29","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/","title":{"rendered":"Treffen Sie die Freiwilligen: Madlauget"},"content":{"rendered":"<p><strong>LEBENDES MUSEUM \/ wiederkehrend \/ Kostenlos bei bezahltem Eintritt<\/strong><\/p>\n<p>Treffen Sie die Food Guild im Madens Hus, wo mit altem, historischem Geschirr und den alten Werkzeugen von damals gearbeitet wird. Je nach Zeitpunkt Ihres Museumsbesuchs arbeiten die ehrenamtlichen Mitarbeiter der Kulinarik-Gilde des Museums mit und zu unterschiedlichen Gerichten und Epochen.<\/p>\n<p>Doch egal, was sie tun, f\u00fcr einen netten Dialog \u00fcber das Kochen und die historischen Rezepte, mit denen sie arbeiten, haben sie immer Zeit \u2013 und meist gibt es auch Kostproben nach der Fertigstellung der Gerichte.<\/p>","protected":false},"excerpt":{"rendered":"<p>LEBENDES MUSEUM \/ wiederkehrend \/ Kostenlos bei Zahlung des Eintrittspreises. Treffen Sie die Lebensmittelzunft im Madens Hus, wo sie mit altem historischem Geschirr und den alten Werkzeugen von damals arbeiten\u2026<\/p>","protected":false},"author":17,"featured_media":22531,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[46,48],"class_list":["post-26925","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-arrangementer","tribe_events_cat-levende-museum","cat_arrangementer","cat_levende-museum","tribe-recurring-event","tribe-recurring-event-child","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f8d de frivillige: Madlauget - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"M\u00f8d madlauget hver tirsdag p\u00e5 Det Gr\u00f8nne Museum p\u00e5 Djursland. De laver historiske opskrifter og der er smagspr\u00f8ver n\u00e5r retterne er f\u00e6rdige.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-der-lebensmittelgilde-2026-04-21\/2026-09-29\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f8d de frivillige: Madlauget - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"M\u00f8d madlauget hver tirsdag p\u00e5 Det Gr\u00f8nne Museum p\u00e5 Djursland. De laver historiske opskrifter og der er smagspr\u00f8ver n\u00e5r retterne er f\u00e6rdige.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-der-lebensmittelgilde-2026-04-21\/2026-09-29\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T09:42:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/07\/madens-hus-og-madlaug-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/\",\"name\":\"M\u00f8d de frivillige: Madlauget - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/madens-hus-og-madlaug-scaled.jpg\",\"datePublished\":\"2026-04-07T06:38:32+00:00\",\"dateModified\":\"2026-04-10T09:42:21+00:00\",\"description\":\"M\u00f8d madlauget hver tirsdag p\u00e5 Det Gr\u00f8nne Museum p\u00e5 Djursland. De laver historiske opskrifter og der er smagspr\u00f8ver n\u00e5r retterne er f\u00e6rdige.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/madens-hus-og-madlaug-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/madens-hus-og-madlaug-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Madlauget laver kartoffelklatkager med g\u00e6sterne i Madens Hus.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-09-29\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00f8d de frivillige: Madlauget\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/moed-de-frivillige-madlauget-2026-04-21\\\/2026-04-21\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00f8d de frivillige: Madlauget\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Treffen Sie die Freiwilligen: The Food Guild - The Green Museum","description":"Treffen Sie die Lebensmittelgilde jeden Dienstag im Gr\u00fcnen Museum auf Djursland. Es werden historische Rezepte zubereitet und nach der Fertigstellung der Gerichte gibt es Verkostungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-der-lebensmittelgilde-2026-04-21\/2026-09-29\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00f8d de frivillige: Madlauget - Det Gr\u00f8nne Museum","og_description":"M\u00f8d madlauget hver tirsdag p\u00e5 Det Gr\u00f8nne Museum p\u00e5 Djursland. De laver historiske opskrifter og der er smagspr\u00f8ver n\u00e5r retterne er f\u00e6rdige.","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/treffen-sie-die-freiwilligen-der-lebensmittelgilde-2026-04-21\/2026-09-29\/","og_site_name":"Det Gr\u00f8nne Museum","article_modified_time":"2026-04-10T09:42:21+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/07\/madens-hus-og-madlaug-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/","name":"Treffen Sie die Freiwilligen: The Food Guild - The Green Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/07\/madens-hus-og-madlaug-scaled.jpg","datePublished":"2026-04-07T06:38:32+00:00","dateModified":"2026-04-10T09:42:21+00:00","description":"Treffen Sie die Lebensmittelgilde jeden Dienstag im Gr\u00fcnen Museum auf Djursland. Es werden historische Rezepte zubereitet und nach der Fertigstellung der Gerichte gibt es Verkostungen.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/07\/madens-hus-og-madlaug-scaled.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/07\/madens-hus-og-madlaug-scaled.jpg","width":2560,"height":1707,"caption":"Madlauget laver kartoffelklatkager med g\u00e6sterne i Madens Hus."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-09-29\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"M\u00f8d de frivillige: Madlauget","item":"https:\/\/detgroennemuseum.dk\/begivenhed\/moed-de-frivillige-madlauget-2026-04-21\/2026-04-21\/"},{"@type":"ListItem","position":4,"name":"M\u00f8d de frivillige: Madlauget"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/26925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/26925\/revisions"}],"predecessor-version":[{"id":27428,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/26925\/revisions\/27428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/22531"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=26925"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=26925"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=26925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}