{"id":10002138,"date":"2024-12-02T12:48:36","date_gmt":"2024-12-02T11:48:36","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?post_type=tribe_events&#038;p=24732"},"modified":"2024-12-02T12:48:36","modified_gmt":"2024-12-02T11:48:36","slug":"kostenlose-weihnachtsfuhrung-weihnachtsbrauche-im-wandel-der-zeit","status":"publish","type":"tribe_events","link":"https:\/\/detgroennemuseum.dk\/de\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/","title":{"rendered":"Kostenlose Weihnachtsf\u00fchrung \u2013 Weihnachtsbr\u00e4uche im Wandel der Zeit"},"content":{"rendered":"<p><strong>Kostenlose Weihnachtsf\u00fchrung \u2013 Weihnachtsbr\u00e4uche im Wandel der Zeit<\/strong><\/p>\n<p>Warum sollte man am Heiligabend nicht in den Stall gehen? Was ist die Geschichte hinter dem Weihnachtsbock und wie wurde das alte Weihnachtsfest eigentlich modern?<\/p>\n<p>Preis: Kostenlos mit der Eintrittskarte<\/p>\n<p>Uhrzeit: 11:00 und 13:30 \u2013 Dauer 45 Minuten.<\/p>\n<p>Kommen Sie rechtzeitig. Wir freuen uns darauf, Weihnachtsgeschichten mit Ihnen zu teilen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Kostenlose Weihnachtsf\u00fchrung \u2013 Weihnachtsbr\u00e4uche im Wandel der Zeit Warum sollte man an Heiligabend nicht in den Stall gehen? Was ist die Geschichte hinter dem Weihnachtsbock und wie wurde das alte Weihnachtsfest eigentlich modern? Preis: Kostenlos\u2026<\/p>","protected":false},"author":17,"featured_media":24733,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[45],"class_list":["post-10002138","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-rundvisninger","cat_rundvisninger","tribe-recurring-event","tribe-recurring-event-parent","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gratis julerundvisning \u2013 Julens skikke gennem tiderne - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Kom til julerundvisning for b\u00f8rn og voksne med \u201dJulefort\u00e6ller\u201d, historiker og museumsinspekt\u00f8r Lola W\u00f8hlk Hansen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/kostenlose-weihnachtsfuhrung-weihnachtsbrauche-im-wandel-der-zeit\/2024-12-15\/1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gratis julerundvisning \u2013 Julens skikke gennem tiderne - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Kom til julerundvisning for b\u00f8rn og voksne med \u201dJulefort\u00e6ller\u201d, historiker og museumsinspekt\u00f8r Lola W\u00f8hlk Hansen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/ereignis\/kostenlose-weihnachtsfuhrung-weihnachtsbrauche-im-wandel-der-zeit\/2024-12-15\/1\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/juletableau-til-rundvisning-hjemmeside.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1129\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/\",\"name\":\"Gratis julerundvisning \u2013 Julens skikke gennem tiderne - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/juletableau-til-rundvisning-hjemmeside.jpg\",\"datePublished\":\"2024-12-02T11:48:36+00:00\",\"description\":\"Kom til julerundvisning for b\u00f8rn og voksne med \u201dJulefort\u00e6ller\u201d, historiker og museumsinspekt\u00f8r Lola W\u00f8hlk Hansen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/juletableau-til-rundvisning-hjemmeside.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/juletableau-til-rundvisning-hjemmeside.jpg\",\"width\":1500,\"height\":1129,\"caption\":\"Tableau fra udstillingen Alletiders Jul\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/begivenhed\\\/gratis-julerundvisning-julens-skikke-gennem-tiderne\\\/2024-12-15\\\/1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Begivenheder\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/detsker\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gratis julerundvisning \u2013 Julens skikke gennem tiderne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kostenlose Weihnachtsf\u00fchrung \u2013 Weihnachtsbr\u00e4uche im Wandel der Zeit - Das Gr\u00fcne Museum","description":"Kommen Sie zu einer Weihnachtsf\u00fchrung f\u00fcr Kinder und Erwachsene mit der \u201eWeihnachtsgeschichtenerz\u00e4hlerin\u201c, Historikerin und Museumskuratorin Lola W\u00f8hlk Hansen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/kostenlose-weihnachtsfuhrung-weihnachtsbrauche-im-wandel-der-zeit\/2024-12-15\/1\/","og_locale":"de_DE","og_type":"article","og_title":"Gratis julerundvisning \u2013 Julens skikke gennem tiderne - Det Gr\u00f8nne Museum","og_description":"Kom til julerundvisning for b\u00f8rn og voksne med \u201dJulefort\u00e6ller\u201d, historiker og museumsinspekt\u00f8r Lola W\u00f8hlk Hansen!","og_url":"https:\/\/detgroennemuseum.dk\/de\/ereignis\/kostenlose-weihnachtsfuhrung-weihnachtsbrauche-im-wandel-der-zeit\/2024-12-15\/1\/","og_site_name":"Det Gr\u00f8nne Museum","og_image":[{"width":1500,"height":1129,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/juletableau-til-rundvisning-hjemmeside.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/","url":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/","name":"Kostenlose Weihnachtsf\u00fchrung \u2013 Weihnachtsbr\u00e4uche im Wandel der Zeit - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/juletableau-til-rundvisning-hjemmeside.jpg","datePublished":"2024-12-02T11:48:36+00:00","description":"Kommen Sie zu einer Weihnachtsf\u00fchrung f\u00fcr Kinder und Erwachsene mit der \u201eWeihnachtsgeschichtenerz\u00e4hlerin\u201c, Historikerin und Museumskuratorin Lola W\u00f8hlk Hansen!","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/juletableau-til-rundvisning-hjemmeside.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/12\/juletableau-til-rundvisning-hjemmeside.jpg","width":1500,"height":1129,"caption":"Tableau fra udstillingen Alletiders Jul"},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/begivenhed\/gratis-julerundvisning-julens-skikke-gennem-tiderne\/2024-12-15\/1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Begivenheder","item":"https:\/\/detgroennemuseum.dk\/detsker\/"},{"@type":"ListItem","position":3,"name":"Gratis julerundvisning \u2013 Julens skikke gennem tiderne"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/10002138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":0,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events\/10002138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/24733"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=10002138"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=10002138"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10002138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}