{"id":27571,"date":"2026-05-13T10:32:12","date_gmt":"2026-05-13T08:32:12","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=27571"},"modified":"2026-05-13T10:32:12","modified_gmt":"2026-05-13T08:32:12","slug":"verkostungen-von-kunsthandwerk-und-rodeo-bullen-auf-der-landwirtschaftsmesse","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/","title":{"rendered":"Verkostungen, Kunsthandwerk und Rodeobullen auf der Landwirtschaftsmesse"},"content":{"rendered":"<h3>Verkostungen, Kunsthandwerk und Rodeobullen auf der Landwirtschaftsmesse<\/h3>\n<div id=\"attachment_27572\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-27572\" class=\"size-medium wp-image-27572 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor-600x400.jpg.webp\" alt=\"Kind und Freiwilliger der Traktorwerkstatt sitzen auf einem Traktor.\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor-18x12.jpg.webp 18w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor-64x43.jpg.webp 64w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Barn-paa-traktor.jpg.webp 1500w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-27572\" class=\"wp-caption-text\">Es gibt unz\u00e4hlige tolle Erlebnisse f\u00fcr Kinder jeden Alters.<\/p><\/div>\n<p><strong>Wenn am Freitag, den 22. Mai, die Landwirtschaftsmesse er\u00f6ffnet wird, befindet sich das Gr\u00fcne Museum wieder auf dem Platz an der Gl. Estrup \u2013 und wie immer wird das Museumsgel\u00e4nde voller Leben sein, mit dem Duft historischer kulinarischer Erlebnisse, altem Handwerk und Aktivit\u00e4ten f\u00fcr die ganze Familie.<\/strong><\/p>\n<p>Die Mitarbeiter des Museums und zahlreiche Freiwillige stehen von 10 bis 16 Uhr zur Verf\u00fcgung und laden die G\u00e4ste ein, die Handwerksk\u00fcnste, Gemeinschaften und Geschichten, die einen wichtigen Teil der lebendigen Kulturgeschichte des Green Museums ausmachen, hautnah kennenzulernen.<\/p>\n<p><strong>Verkostungen, Kunsthandwerk und lebendige Geschichten<\/strong><\/p>\n<p>Auf dem Museumsgel\u00e4nde k\u00f6nnen die G\u00e4ste eine Vielzahl der Z\u00fcnfte des Museums kennenlernen, die an beiden Tagen Wissen, Verkostungen und gute Laune verbreiten werden.<\/p>\n<p>Die Brauergilde bietet Bierproben an, w\u00e4hrend die Lebensmittelgilde historische Rezepte und Geschichten zur Essensgeschichte pr\u00e4sentiert. Bei den Imkern kann man die Bienen aus n\u00e4chster N\u00e4he erleben und Honig probieren, und die Metzgergilde heizt die R\u00e4ucherei an und bietet Kostproben an.<\/p>\n<p>Die Milchbauern bringen verschiedene K\u00e4sesorten zur Verkostung mit, w\u00e4hrend die Bogensch\u00fctzenzunft die Herstellung von Holzb\u00f6gen in fr\u00fcheren Zeiten demonstriert. Die Schmiede arbeiten an der Freiluft-Esse, wo das hei\u00dfe Eisen geformt wird.<\/p>\n<p>Karle- og Pigelauget pr\u00e4sentiert auf der Messe ebenfalls traditionelle Techniken und Arbeitsmethoden. Hier k\u00f6nnen Besucher eine Dreschmaschine in Aktion erleben, ihr eigenes Seil herstellen oder einen Mini-Strohballen binden. Gleichzeitig f\u00fcllt die Traktorenwerkstatt das Gel\u00e4nde mit alten Traktoren und Geschichten \u00fcber Landmaschinen aus verschiedenen Epochen.<\/p>\n<p>Alle Aktivit\u00e4ten und Verkostungen in den Gilden sind kostenlos.<\/p>\n<p><strong>Aktivit\u00e4ten mit Tempo, Lachen und Herausforderungen<\/strong><\/p>\n<p>Das Museumspersonal hat au\u00dferdem eine Reihe von Aktivit\u00e4ten f\u00fcr Kinder, Jugendliche und Erwachsene vorbereitet, bei denen Lernen und Spielen Hand in Hand gehen.<\/p>\n<p>Die diesj\u00e4hrige Hauptattraktion ist der Rodeo-Bulle, auf dem die G\u00e4ste ihr Gleichgewicht testen und sehen k\u00f6nnen, wie lange sie sich im Sattel halten k\u00f6nnen. Traditionell besteht auch die M\u00f6glichkeit, sich im Bogenschie\u00dfen zu versuchen. Beide Aktivit\u00e4ten kosten 20 Kronen.<\/p>\n<p>Dar\u00fcber hinaus kann die ganze Familie oder eine Gruppe von Freunden im \u201cJahrmarktswettbewerb\u201d gegeneinander antreten \u2013 einer Sammlung lustiger und herausfordernder Aktivit\u00e4ten, die von den Wettk\u00e4mpfen und Kraftproben auf alten Jahrm\u00e4rkten inspiriert sind.<\/p>\n<p>Hier kannst du Stelzenlaufen, Ballwerfen, Tauziehen und Balancieren auf einem Baumstamm ausprobieren. Du kannst auch deine Kraft beim \u201cZiehen wie ein Pferd\u201d testen oder mit gro\u00dfen Holzst\u00fccken bauen.<\/p>\n<p><strong>Erlebnisse f\u00fcr die ganze Familie<\/strong><\/p>\n<p>Der Bereich \u201eGr\u00fcnes Museum\u201c auf der Landwirtschaftsmesse wurde als Ort geschaffen, an dem G\u00e4ste jeden Alters Geschichte mit den H\u00e4nden erleben, die Vergangenheit schmecken und sich an alten Handwerksk\u00fcnsten und Spielen versuchen k\u00f6nnen.<\/p>\n<p>Es gibt Raum f\u00fcr Besinnung, Lachen, Wettbewerbe und gute Gespr\u00e4che \u2013 inmitten der Atmosph\u00e4re der diesj\u00e4hrigen Landwirtschaftsmesse (besuchen Sie die Website der Landwirtschaftsmesse). <a href=\"https:\/\/landbrugsmessen.dk\/\" target=\"_blank\" rel=\"noopener\">Hier<\/a>).<br \/>\n<span style=\"color: #003300;\"><strong>Wir freuen uns, Sie am Freitag und Samstag von 10 bis 16 Uhr begr\u00fc\u00dfen zu d\u00fcrfen.<\/strong><\/span><\/p>\n<div id=\"attachment_27574\" style=\"width: 610px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-27574\" class=\"size-medium wp-image-27574 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning-600x452.jpg.webp\" alt=\"Kind versucht Seilspringen in Karle-og Pigelauget.\" width=\"600\" height=\"452\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning-600x452.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning-1024x771.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning-768x578.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning-16x12.jpg.webp 16w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning-64x48.jpg.webp 64w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2026\/05\/Rebslagning.jpg.webp 1500w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/452;\" \/><p id=\"caption-attachment-27574\" class=\"wp-caption-text\">Eine der beliebtesten Aktivit\u00e4ten ist das Seilspringen in Karle- og Pigelauget.<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Verkostungen, Kunsthandwerk und Rodeo-Bullen auf der Landwirtschaftsmesse. Wenn die Landwirtschaftsmesse am Freitag, den 22. Mai, ihre Pforten \u00f6ffnet, wird das Green Museum wieder auf dem Marktplatz in Gl. Estrup vertreten sein \u2013 und das Museum ist dort stets gut besucht\u2026<\/p>","protected":false},"author":17,"featured_media":27572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-27571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Som altid fylder museets omr\u00e5de godt med b\u00e5de liv, duften af historiske madoplevelser, gamle h\u00e5ndv\u00e6rk og aktiviteter for hele familien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/verkostungen-von-kunsthandwerk-und-rodeo-bullen-auf-der-landwirtschaftsmesse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Som altid fylder museets omr\u00e5de godt med b\u00e5de liv, duften af historiske madoplevelser, gamle h\u00e5ndv\u00e6rk og aktiviteter for hele familien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/verkostungen-von-kunsthandwerk-und-rodeo-bullen-auf-der-landwirtschaftsmesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T08:32:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2026\/05\/Barn-paa-traktor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen\",\"datePublished\":\"2026-05-13T08:32:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/\"},\"wordCount\":540,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Barn-paa-traktor.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/\",\"name\":\"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Barn-paa-traktor.jpg\",\"datePublished\":\"2026-05-13T08:32:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"Som altid fylder museets omr\u00e5de godt med b\u00e5de liv, duften af historiske madoplevelser, gamle h\u00e5ndv\u00e6rk og aktiviteter for hele familien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Barn-paa-traktor.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Barn-paa-traktor.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Der er masser af gode oplevelser for b\u00f8rn i alle aldre.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verkostungen, Kunsthandwerk und Rodeobullen auf der Landwirtschaftsmesse \u2013 Das Gr\u00fcne Museum","description":"Wie immer pulsiert das Museumsgel\u00e4nde vor Leben, der Duft historischer Speisen, altes Handwerk und Aktivit\u00e4ten f\u00fcr die ganze Familie liegen in der Luft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/verkostungen-von-kunsthandwerk-und-rodeo-bullen-auf-der-landwirtschaftsmesse\/","og_locale":"de_DE","og_type":"article","og_title":"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen - Det Gr\u00f8nne Museum","og_description":"Som altid fylder museets omr\u00e5de godt med b\u00e5de liv, duften af historiske madoplevelser, gamle h\u00e5ndv\u00e6rk og aktiviteter for hele familien.","og_url":"https:\/\/detgroennemuseum.dk\/de\/verkostungen-von-kunsthandwerk-und-rodeo-bullen-auf-der-landwirtschaftsmesse\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2026-05-13T08:32:12+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2026\/05\/Barn-paa-traktor.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen","datePublished":"2026-05-13T08:32:12+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/"},"wordCount":540,"image":{"@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2026\/05\/Barn-paa-traktor.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/","url":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/","name":"Verkostungen, Kunsthandwerk und Rodeobullen auf der Landwirtschaftsmesse \u2013 Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2026\/05\/Barn-paa-traktor.jpg","datePublished":"2026-05-13T08:32:12+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"Wie immer pulsiert das Museumsgel\u00e4nde vor Leben, der Duft historischer Speisen, altes Handwerk und Aktivit\u00e4ten f\u00fcr die ganze Familie liegen in der Luft.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2026\/05\/Barn-paa-traktor.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2026\/05\/Barn-paa-traktor.jpg","width":1500,"height":1000,"caption":"Der er masser af gode oplevelser for b\u00f8rn i alle aldre."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/smagsproever-haandvaerk-og-rodeotyr-paa-landbrugsmessen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Smagspr\u00f8ver, h\u00e5ndv\u00e6rk og rodeotyr p\u00e5 Landbrugsmessen"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/27571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=27571"}],"version-history":[{"count":2,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/27571\/revisions"}],"predecessor-version":[{"id":27575,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/27571\/revisions\/27575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/27572"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=27571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=27571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=27571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}