{"id":24135,"date":"2024-06-06T12:30:56","date_gmt":"2024-06-06T10:30:56","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=24135"},"modified":"2024-06-28T09:01:56","modified_gmt":"2024-06-28T07:01:56","slug":"randers-theater-und-das-grune-museum-in-zusammenarbeit","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/randers-teater-og-det-groenne-museum-i-samarbejde\/","title":{"rendered":"Randers Theater arbeitet mit dem Green Museum an der Auff\u00fchrung Miss Jensens Kochbuch"},"content":{"rendered":"<h3>Randers Theater arbeitet mit dem Green Museum an der Auff\u00fchrung Miss Jensens Kochbuch<\/h3>\n<div id=\"attachment_24136\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-24136\" class=\"size-medium wp-image-24136 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2024\/06\/Randers-Teater-3-600x400.jpg.webp\" alt=\"von links: Anne Bjerrek\u00e6r, Direktorin des Gr\u00fcnen Museums, Bettina Buhl, Museumskuratorin und Lebensmittelhistorikerin und Peter Westphael, Theaterdirektor am Randers Teater.\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2024\/06\/Randers-Teater-3-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2024\/06\/Randers-Teater-3-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2024\/06\/Randers-Teater-3-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2024\/06\/Randers-Teater-3-64x43.jpg.webp 64w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2024\/06\/Randers-Teater-3.jpg.webp 1500w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-24136\" class=\"wp-caption-text\">von links: Anne Bjerrek\u00e6r, Direktorin des Gr\u00fcnen Museums,<br \/>Bettina Buhl, Museumskuratorin und Lebensmittelhistorikerin und<br \/>Peter Westphael, Theaterdirektor am Randers Theater.<\/p><\/div>\n<p><strong>Randers Teater freut sich, im Zusammenhang mit unserer bevorstehenden Auff\u00fchrung \u201eMiss Jensens Kochbuch\u201c eine einzigartige Zusammenarbeit mit dem Gr\u00fcnen Museum pr\u00e4sentieren zu k\u00f6nnen. Die Auff\u00fchrung hat am 29. August Premiere und bringt dem Publikum das kulinarische Erbe durch Theater- und Essenserlebnisse n\u00e4her.<\/strong><\/p>\n<p>Wir sind eine enge Zusammenarbeit mit der Museumskuratorin und Lebensmittelhistorikerin Bettina Buhl eingegangen, die f\u00fcr ihr fundiertes Wissen \u00fcber historische Gerichte bekannt ist. Bettina Buhl hat bereits bei der TV2-Serie \u201eBadehotellet\u201c mitgewirkt und daf\u00fcr gesorgt, dass die kulinarischen Szenen historisch korrekt sind. Vor Kurzem gab sie ihr Deb\u00fct als Fernsehmoderatorin in der neuen Kochsendung \u201eBadehotellets Kokkeskole\u201c von TV2, was ihre Kompetenzen und Kommunikationsf\u00e4higkeiten noch weiter unterstreicht.<\/p>\n<p>In \u201eMiss Jensens Kochbuch\u201c hat Bettina Buhl mit dem Regisseur und Dramatiker Martin Lyngbo zusammengearbeitet, um sicherzustellen, dass der kulinarische Aspekt der Auff\u00fchrung authentisch und korrekt ist. Ihr Beitrag zur Zusammenstellung des Men\u00fcs, das das Publikum vor der Vorstellung erwerben kann, war von unsch\u00e4tzbarem Wert. Dieses Men\u00fc wurde sorgf\u00e4ltig ausgew\u00e4hlt, um in das Universum der Show zu passen und ein umfassendes Erlebnis der historischen Esskultur zu bieten.<\/p>\n<p>Die Teilnahme von Bettina Buhl an diesem Projekt zeigt nicht nur ihre gro\u00dfen beruflichen F\u00e4higkeiten, sondern auch das Engagement des Gr\u00fcnen Museums, das Verst\u00e4ndnis f\u00fcr Kulturgeschichte durch Essen zu f\u00f6rdern. Ihre F\u00e4higkeit, historisches Wissen \u00fcber die Esskultur auf spannende und lebendige Weise zu vermitteln, ist sowohl durch ihre Arbeit im Museum in Djursland als auch im nationalen Fernsehen bekannt.<\/p>\n<p>\u201eDie Zusammenarbeit mit Bettina Buhl und dem Gr\u00fcnen Museum war eine fantastische Erfahrung\u201c, sagt Theaterdirektor Peter Westphael. \u201eIhre Einblicke in die historische Esskultur verleihen der Auff\u00fchrung eine au\u00dfergew\u00f6hnlich authentische Dimension, die unser Publikum mit Sicherheit begeistern wird. Wir freuen uns darauf, dieses einzigartige Theater- und Essenserlebnis mit Ihnen allen zu teilen.\u201c<\/p>\n<p>Auch die Direktorin des Gr\u00fcnen Museums, Anne Bjerrek\u00e6r, freut sich \u00fcber diese neue lokale Zusammenarbeit zwischen dem Randers Theater und dem Gr\u00fcnen Museum.<\/p>\n<p>\u201eDie Zusammenarbeit an diesem neuen St\u00fcck war sehr faszinierend und ist hoffentlich nur die erste von mehreren zuk\u00fcnftigen Kooperationen zwischen Randers Teater und uns. Die Tatsache, dass zwei Kulturinstitutionen hier zu einer solchen Zusammenarbeit zusammenkommen, bringt auf ganzer Linie nur Gewinner hervor\u201c, sagt Anne Bjerrek\u00e6r.<\/p>\n<p>Wir freuen uns, unser Publikum zu einer Vorstellung begr\u00fc\u00dfen zu d\u00fcrfen, die es nicht nur um Theatererlebnisse bereichert, sondern auch auf eine kulinarische Zeitreise mitnimmt.<\/p>\n<p><a href=\"https:\/\/randersteater.dk\/program\/froken-jensens-kogebog\/\" target=\"_blank\" rel=\"noopener\">Lesen Sie mehr \u00fcber die Auff\u00fchrung auf der Website des Randers Teater.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Das Randers Theatre arbeitet bei der Auff\u00fchrung \u201eMiss Jensens Kochbuch\u201c mit dem Green Museum zusammen. Das Randers Theatre freut sich, eine einzigartige Zusammenarbeit mit dem Green Museum pr\u00e4sentieren zu k\u00f6nnen.<\/p>","protected":false},"author":17,"featured_media":24136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-24135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Randers Teater har den store gl\u00e6de at kunne pr\u00e6sentere et unikt samarbejde med Det Gr\u00f8nne Museum p\u00e5 Djursland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/randers-theater-und-das-grune-museum-in-zusammenarbeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Randers Teater har den store gl\u00e6de at kunne pr\u00e6sentere et unikt samarbejde med Det Gr\u00f8nne Museum p\u00e5 Djursland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/randers-theater-und-das-grune-museum-in-zusammenarbeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T10:30:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-28T07:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/06\/Randers-Teater-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog\",\"datePublished\":\"2024-06-06T10:30:56+00:00\",\"dateModified\":\"2024-06-28T07:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/\"},\"wordCount\":488,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Randers-Teater-3.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/\",\"name\":\"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Randers-Teater-3.jpg\",\"datePublished\":\"2024-06-06T10:30:56+00:00\",\"dateModified\":\"2024-06-28T07:01:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"Randers Teater har den store gl\u00e6de at kunne pr\u00e6sentere et unikt samarbejde med Det Gr\u00f8nne Museum p\u00e5 Djursland.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Randers-Teater-3.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Randers-Teater-3.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"fra venstre: Anne Bjerrek\u00e6r, direkt\u00f8r for Det Gr\u00f8nne Museum, Bettina Buhl, museumsinspekt\u00f8r og madhistoriker og Peter Westphael, teaterdirekt\u00f8r p\u00e5 Randers Teater.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/randers-teater-og-det-groenne-museum-i-samarbejde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Randers Theater arbeitet mit dem Green Museum an der Auff\u00fchrung Miss Jensens Kochbuch - The Green Museum","description":"Randers Teater freut sich, eine einzigartige Zusammenarbeit mit dem Gr\u00fcnen Museum auf Djursland pr\u00e4sentieren zu k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/randers-theater-und-das-grune-museum-in-zusammenarbeit\/","og_locale":"de_DE","og_type":"article","og_title":"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog - Det Gr\u00f8nne Museum","og_description":"Randers Teater har den store gl\u00e6de at kunne pr\u00e6sentere et unikt samarbejde med Det Gr\u00f8nne Museum p\u00e5 Djursland.","og_url":"https:\/\/detgroennemuseum.dk\/de\/randers-theater-und-das-grune-museum-in-zusammenarbeit\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2024-06-06T10:30:56+00:00","article_modified_time":"2024-06-28T07:01:56+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/06\/Randers-Teater-3.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog","datePublished":"2024-06-06T10:30:56+00:00","dateModified":"2024-06-28T07:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/"},"wordCount":488,"image":{"@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/06\/Randers-Teater-3.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/","url":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/","name":"Randers Theater arbeitet mit dem Green Museum an der Auff\u00fchrung Miss Jensens Kochbuch - The Green Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/06\/Randers-Teater-3.jpg","datePublished":"2024-06-06T10:30:56+00:00","dateModified":"2024-06-28T07:01:56+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"Randers Teater freut sich, eine einzigartige Zusammenarbeit mit dem Gr\u00fcnen Museum auf Djursland pr\u00e4sentieren zu k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/06\/Randers-Teater-3.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2024\/06\/Randers-Teater-3.jpg","width":1500,"height":1000,"caption":"fra venstre: Anne Bjerrek\u00e6r, direkt\u00f8r for Det Gr\u00f8nne Museum, Bettina Buhl, museumsinspekt\u00f8r og madhistoriker og Peter Westphael, teaterdirekt\u00f8r p\u00e5 Randers Teater."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/randers-teater-og-det-groenne-museum-i-samarbejde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Randers Teater indg\u00e5r samarbejde med Det Gr\u00f8nne Museum om forestillingen Fr\u00f8ken Jensens Kogebog"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/24135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=24135"}],"version-history":[{"count":6,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/24135\/revisions"}],"predecessor-version":[{"id":24200,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/24135\/revisions\/24200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/24136"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=24135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=24135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=24135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}