{"id":22703,"date":"2023-09-30T16:15:38","date_gmt":"2023-09-30T14:15:38","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=22703"},"modified":"2023-09-30T09:23:41","modified_gmt":"2023-09-30T07:23:41","slug":"lebendiger-samstag-ein-tag-voller-erlebnisse","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/levende-loerdag-en-dag-fyldt-med-oplevelser\/","title":{"rendered":"Lebendiger Samstag im Gr\u00fcnen Museum: Ein Tag voller Erlebnisse"},"content":{"rendered":"<h3>Lebendiger Samstag im Gr\u00fcnen Museum: Ein Tag voller Erlebnisse<\/h3>\n<div id=\"attachment_22704\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-22704\" class=\"size-medium wp-image-22704 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/09\/Smedjen-7-600x400.jpg.webp\" alt=\"Arbeiten in der Schmiede\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/09\/Smedjen-7-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/09\/Smedjen-7-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/09\/Smedjen-7-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/09\/Smedjen-7-64x43.jpg.webp 64w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/09\/Smedjen-7.jpg.webp 1500w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-22704\" class=\"wp-caption-text\">Die ehrenamtlichen Helfer sind immer ein beliebtes Erlebnis \u2013 hier k\u00f6nnt ihr bei der Arbeit in der Schmiede zusehen.<\/p><\/div>\n<p><strong>An ausgew\u00e4hlten Samstagen verwandelt sich das Gr\u00fcne Museum in ein lebendiges Zentrum f\u00fcr Aktivit\u00e4ten und Geschmackserlebnisse. \u201eLiving Saturday\u201c ist eine Initiative des Museums, bei der Freiwilligengruppen Besucher einladen, auf ganz neue Weise in die Jagd-, Forst-, Landwirtschafts- und Lebensmittelgeschichte D\u00e4nemarks einzutauchen. Das n\u00e4chste Mal ist Samstag, der 7. Oktober.<\/strong><\/p>\n<p>Eine der vielen Initiativen ist die Polakhusgruppen, die Besucher zu einem netten Gespr\u00e4ch und einer Tasse Kaffeeersatz im Polakhus willkommen hei\u00dft. Hier k\u00f6nnen Sie einen wichtigen Teil der d\u00e4nischen Geschichte erleben und einen Eindruck davon bekommen, wie Ersatzkaffee fr\u00fcher geschmeckt hat.<\/p>\n<p>F\u00fcr Technikinteressierte ist der Besuch der Traktorenwerkstatt ein Muss. Besucher haben die M\u00f6glichkeit, mit den Mechanikern zu sprechen und etwas \u00fcber die alten Traktoren zu erfahren, die jahrzehntelang den Grundstein der d\u00e4nischen Landwirtschaft bildeten.<\/p>\n<p>Die Schmiedezunft ist ein wahres Mekka f\u00fcr alle, die das Handwerk lieben. Hier k\u00f6nnen Sie mit den Schmieden in der Esse sprechen und Einblicke in die edle Schmiedekunst gewinnen, die noch immer mit Stolz ausge\u00fcbt wird.<\/p>\n<p>Die Besuchermoderatoren des Besuchermagazins sind immer bereit, faszinierende Geschichten \u00fcber die Ausstellungen und Sammlungen des Museums zu erz\u00e4hlen. Sie sind bestrebt, den Besuch so lehrreich und unvergesslich wie m\u00f6glich zu gestalten.<\/p>\n<p>Die Historische Werkstatt ist die Heimat mehrerer spannender Gruppen. Die Imkerzunft stellt Rahmen her, formt Wachs und verkauft lokal produzierten Honig. Die Metzgergilde verw\u00f6hnt die Geschmacksknospen mit ger\u00e4ucherter Wildwurst, w\u00e4hrend die Lebensmittelgilde Kostproben k\u00f6stlicher Amager-Suppe anbietet.<\/p>\n<p>In der Ausstellung Stort k\u00f6nnen Sie die Bogensch\u00fctzengilde erleben, die die Kunst der Herstellung von Pfeilen und Sehnen vorf\u00fchrt. Die Forstinnung gew\u00e4hrt Einblicke in die Welt der Forstarbeiter und vermittelt Wissen \u00fcber die Sch\u00e4tze der Natur.<\/p>\n<p>Der Garten ist eine Oase der Ruhe und Sch\u00f6nheit. Um 11:00, 12:30 und 14:00 Uhr steht die Lebensmittelhistorikerin Bettina Buhl f\u00fcr Einf\u00fchrungen bereit, bei denen die Besucher im Garten viele spannende Geschichten h\u00f6ren k\u00f6nnen. Die Einf\u00fchrung beginnt im Museumsshop. Denken Sie daran, dass der Shop auch der perfekte Ort ist, um anschlie\u00dfend ein hei\u00dfes Getr\u00e4nk oder ein Souvenir zu kaufen, damit Sie eine bleibende Erinnerung an den Tag haben.<\/p>\n<p>Und das Beste: Alle Aktivit\u00e4ten und Verkostungen sind kostenlos, sobald der Museumseintritt bezahlt ist. Das Gr\u00fcne Museum m\u00f6chte ein integratives Erlebnis f\u00fcr alle schaffen, bei dem Sie das d\u00e4nische Kulturerbe auf unterhaltsame und interaktive Weise erkunden k\u00f6nnen.<\/p>\n<p>Markieren Sie also Ihren Kalender und erleben Sie einen lebendigen Samstag im Gr\u00fcnen Museum, wo Geschichte durch spannende Aktivit\u00e4ten, Verkostungen und leidenschaftliche Freiwillige zum Leben erweckt wird, die ihr Wissen und ihre Liebe f\u00fcr D\u00e4nemarks einzigartiges kulturelles Erbe mit Leidenschaft teilen.<\/p>\n<p>Lesen Sie mehr in unserem Kalender und in den aktuellen Veranstaltungen <a href=\"https:\/\/detgroennemuseum.dk\/de\/es-passiert\/\">Hier.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Lebendiger Samstag im Gr\u00fcnen Museum: Ein Tag voller Erlebnisse An ausgew\u00e4hlten Samstagen verwandelt sich das Gr\u00fcne Museum in ein pulsierendes Zentrum f\u00fcr Aktivit\u00e4ten und Geschmackserlebnisse. \u201eLiving Saturday\u201c ist ein\u2026<\/p>","protected":false},"author":17,"featured_media":22704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-22703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Levende L\u00f8rdag - En dag fyldt med oplevelser.<\/title>\n<meta name=\"description\" content=\"Udvalgte l\u00f8rdage forvandler Det Gr\u00f8nne Museum sig til et pulserende centrum for aktiviteter og smagsoplevelser.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/lebendiger-samstag-ein-tag-voller-erlebnisse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Levende L\u00f8rdag - En dag fyldt med oplevelser.\" \/>\n<meta property=\"og:description\" content=\"Udvalgte l\u00f8rdage forvandler Det Gr\u00f8nne Museum sig til et pulserende centrum for aktiviteter og smagsoplevelser.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/lebendiger-samstag-ein-tag-voller-erlebnisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-30T14:15:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/09\/Smedjen-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Levende L\u00f8rdag p\u00e5 Det Gr\u00f8nne Museum: En dag fyldt med oplevelser\",\"datePublished\":\"2023-09-30T14:15:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/\"},\"wordCount\":489,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Smedjen-7.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/\",\"name\":\"Levende L\u00f8rdag - En dag fyldt med oplevelser.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Smedjen-7.jpg\",\"datePublished\":\"2023-09-30T14:15:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"Udvalgte l\u00f8rdage forvandler Det Gr\u00f8nne Museum sig til et pulserende centrum for aktiviteter og smagsoplevelser.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Smedjen-7.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Smedjen-7.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"De frivillige er altid en popul\u00e6r oplevelse - her ses arbejdet i smedjen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-en-dag-fyldt-med-oplevelser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Levende L\u00f8rdag p\u00e5 Det Gr\u00f8nne Museum: En dag fyldt med oplevelser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samstag leben \u2013 Ein Tag voller Erlebnisse.","description":"An ausgew\u00e4hlten Samstagen verwandelt sich das Gr\u00fcne Museum in ein lebendiges Zentrum f\u00fcr Aktivit\u00e4ten und Geschmackserlebnisse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/lebendiger-samstag-ein-tag-voller-erlebnisse\/","og_locale":"de_DE","og_type":"article","og_title":"Levende L\u00f8rdag - En dag fyldt med oplevelser.","og_description":"Udvalgte l\u00f8rdage forvandler Det Gr\u00f8nne Museum sig til et pulserende centrum for aktiviteter og smagsoplevelser.","og_url":"https:\/\/detgroennemuseum.dk\/de\/lebendiger-samstag-ein-tag-voller-erlebnisse\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2023-09-30T14:15:38+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/09\/Smedjen-7.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Levende L\u00f8rdag p\u00e5 Det Gr\u00f8nne Museum: En dag fyldt med oplevelser","datePublished":"2023-09-30T14:15:38+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/"},"wordCount":489,"image":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/09\/Smedjen-7.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/","url":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/","name":"Samstag leben \u2013 Ein Tag voller Erlebnisse.","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/09\/Smedjen-7.jpg","datePublished":"2023-09-30T14:15:38+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"An ausgew\u00e4hlten Samstagen verwandelt sich das Gr\u00fcne Museum in ein lebendiges Zentrum f\u00fcr Aktivit\u00e4ten und Geschmackserlebnisse.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/09\/Smedjen-7.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/09\/Smedjen-7.jpg","width":1500,"height":1000,"caption":"De frivillige er altid en popul\u00e6r oplevelse - her ses arbejdet i smedjen."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-en-dag-fyldt-med-oplevelser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Levende L\u00f8rdag p\u00e5 Det Gr\u00f8nne Museum: En dag fyldt med oplevelser"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/22703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=22703"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/22703\/revisions"}],"predecessor-version":[{"id":22706,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/22703\/revisions\/22706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/22704"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=22703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=22703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=22703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}