{"id":22258,"date":"2023-05-17T15:29:54","date_gmt":"2023-05-17T13:29:54","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=22258"},"modified":"2023-05-17T15:29:54","modified_gmt":"2023-05-17T13:29:54","slug":"samstag-20-mai-ist-bienentag","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/loerdag-d-20-maj-er-det-biernes-dag\/","title":{"rendered":"Samstag, der 1. Der 20. Mai ist Tag der Biene"},"content":{"rendered":"<h3>Samstag, der 1. Der 20. Mai ist Tag der Biene<\/h3>\n<div id=\"attachment_10788\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-10788\" class=\"size-medium wp-image-10788 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2020\/02\/bilaug-10-600x400.jpg.webp\" alt=\"Der Bienenstand befindet sich im historischen Bienenstand des Gr\u00fcnen Museums in Gammel Estrup.\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2020\/02\/bilaug-10-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/02\/bilaug-10-1024x683.jpg 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/02\/bilaug-10-768x512.jpg 768w, https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/02\/bilaug-10-1536x1024.jpg 1536w, https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/02\/bilaug-10-668x445.jpg 668w, https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/02\/bilaug-10-1336x890.jpg 1336w, https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/02\/bilaug-10.jpg 1920w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-10788\" class=\"wp-caption-text\">Die Biene ist unser kleinstes Haustier, hat aber nat\u00fcrlich ihren wichtigen Platz in der Geschichte und im Gr\u00fcnen Museum in Gammel Estrup. Erfahren Sie mehr bei den ehrenamtlichen Helfern im Autoclub.<\/p><\/div>\n<p><strong>Um die Aufmerksamkeit auf die schwierigen Lebensbedingungen der Bienen und ihre gro\u00dfe Bedeutung f\u00fcr die weltweite Nahrungsmittelproduktion zu lenken, hat die UNO den 20. Mai zum Internationalen Tag der Biene erkl\u00e4rt.<\/strong><\/p>\n<p>In diesem Zusammenhang wird die Imkerzunft des Gr\u00fcnen Museums am Samstag, den 20. Mai, im Museum anwesend sein, um \u00fcber die Bienen zu sprechen und die Bienenst\u00f6cke vorzuf\u00fchren.<\/p>\n<p>Sie werden von 12:00 bis 16:00 Uhr dort sein.<\/p>\n<p><strong>Ein wenig \u00fcber die Geschichte der Biene<\/strong><\/p>\n<p>Die Honigbiene ist in D\u00e4nemark heimisch und spielt seit der Eiszeit eine wichtige Rolle bei der Best\u00e4ubung.<\/p>\n<p>Seit der Bronzezeit (1800\u2013500 v. Chr.) verwenden die Menschen Honig und Wachs von Honigbienen, die wild in der Natur lebten. Man geht davon aus, dass die eigentliche Bienenhaltung zu Beginn des Mittelalters begann. Jahr 1100, als die Honigbiene zu einem Haustier wurde und in der N\u00e4he von Bauernh\u00f6fen und H\u00e4usern lebte. Die ersten Bienenst\u00f6cke bestanden aus ausgeh\u00f6hlten Baumst\u00e4mmen, ab dem 16. Jahrhundert kamen auch Bienenst\u00f6cke aus Stroh zum Einsatz.<\/p>\n<p>Im Mittelalter wurde Honig zum S\u00fc\u00dfen und zum Brauen von Met verwendet, w\u00e4hrend Wachs vor allem in katholischen Kirchen und Kl\u00f6stern als Kerzen Verwendung fand. Bis Mitte des 19. Jahrhunderts die heimische Zuckerproduktion auf Basis von Zuckerr\u00fcben begann, war Honig das wichtigste S\u00fc\u00dfungsmittel in d\u00e4nischen Haushalten.<\/p>\n<p>Ende des 19. Jahrhunderts wurde die Bienenhaltung modernisiert, als man begann, Bienen in Bienenst\u00f6cken mit losen Waben zu halten. W\u00e4hrend fr\u00fcher die Bienen get\u00f6tet werden mussten, wenn der Honig aus den W\u00fcrfeln geerntet werden sollte, konnten die Waben nun aus dem Stock entfernt werden. Der Honig wurde dann freigegeben, indem die Waben in handbetriebene Honigzentrifugen gestellt wurden.<\/p>\n<p>Fr\u00fcher waren es vor allem Bauern, Lehrer und Handwerker auf dem Land, die sich mit der Bienenhaltung besch\u00e4ftigten. Nach einem mehrj\u00e4hrigen R\u00fcckgang der Bienenhaltung nach dem Zweiten Weltkrieg erlebt die Bienenhaltung seit der Jahrtausendwende wieder einen Aufschwung. Heute sind es vor allem j\u00fcngere Menschen und Familien in der Stadt, die Bienen halten. Viele Menschen haben Bienenst\u00f6cke in privaten G\u00e4rten, Schreberg\u00e4rten, Hinterh\u00f6fen oder sogar auf den Dachterrassen von Hochh\u00e4usern in gr\u00f6\u00dferen St\u00e4dten.<\/p>\n<p><strong>Spannendes Wissen rund um die Bienen (vor allem zu finden auf der Website biavl.dk \u2013 der Website des d\u00e4nischen Imkerverbandes).<\/strong><\/p>\n<ul>\n<li>Bienen und andere Insekten, die Nutzpflanzen best\u00e4uben, haben f\u00fcr die d\u00e4nische Gesellschaft eine gro\u00dfe wirtschaftliche Bedeutung. Daher wurde gesch\u00e4tzt, dass ihr Best\u00e4ubungswert bei ca. liegt. 3 Milliarden Kronen. f\u00fcr landwirtschaftliche und Obstanbau-Einkommen.<\/li>\n<li>Der Wert der Best\u00e4ubung landwirtschaftlicher Nutzpflanzen durch Bienen ist 30- bis 50-mal h\u00f6her als der Wert ihres Honigs.<\/li>\n<li>Bienen und andere Best\u00e4uber sind f\u00fcr die Nahrungsmittelversorgung, eine nachhaltige Landwirtschaft, die Umwelt und die Artenvielfalt von entscheidender Bedeutung.<\/li>\n<li>Sch\u00e4tzungsweise gibt es in D\u00e4nemark rund 100.000 Bienenv\u00f6lker.<\/li>\n<li>Es k\u00f6nnen ca. 30-50 Kilo Honig\/Bienenvolk\/Jahr geerntet werden \u2013 die Ausbeute schwankt allerdings stark und ist von Faktoren wie Witterung und Angebot an Bl\u00fchpflanzen abh\u00e4ngig.<\/li>\n<li>In den letzten 50 Jahren ist die Landwirtschaft weltweit immer abh\u00e4ngiger von Best\u00e4ubern geworden; die landwirtschaftliche Produktion von best\u00e4uberabh\u00e4ngigen Nutzpflanzen hat sich vervierfacht.<\/li>\n<li>Weltweit sind drei von vier Nutzpflanzen auf Best\u00e4uber angewiesen. Die FAO sch\u00e4tzt, dass 100 Nutzpflanzenarten 90 Prozent der weltweiten Nahrungsmittelproduktion abdecken \u2013 71 davon werden von Bienen best\u00e4ubt.<\/li>\n<li>Die Arbeit der Bienen und anderer Best\u00e4uber tr\u00e4gt positiv zur Artenvielfalt bei. Weltweit sind 87,5 Prozent der bl\u00fchenden Wildpflanzen auf Best\u00e4uber angewiesen.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Samstag, der 1. Der 20. Mai ist Weltbienentag. In dem Versuch, die schwierigen Bedingungen der Bienen und ihre gro\u00dfe Bedeutung f\u00fcr die weltweite Nahrungsmittelproduktion in den Mittelpunkt zu r\u00fccken, \u2026<\/p>","protected":false},"author":17,"featured_media":11801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-22258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u00f8rdag d. 20 maj er det biernes dag - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"FN har udr\u00e5bt d. 20 maj som biernes dag i et fors\u00f8g p\u00e5 at rette fokus p\u00e5 biernes vanskellige vilk\u00e5r, og deres store betydning.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/samstag-20-mai-ist-bienentag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f8rdag d. 20 maj er det biernes dag - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"FN har udr\u00e5bt d. 20 maj som biernes dag i et fors\u00f8g p\u00e5 at rette fokus p\u00e5 biernes vanskellige vilk\u00e5r, og deres store betydning.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/samstag-20-mai-ist-bienentag\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T13:29:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/06\/bilauget-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"L\u00f8rdag d. 20 maj er det biernes dag\",\"datePublished\":\"2023-05-17T13:29:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/\"},\"wordCount\":613,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bilauget-10.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/\",\"name\":\"L\u00f8rdag d. 20 maj er det biernes dag - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bilauget-10.jpg\",\"datePublished\":\"2023-05-17T13:29:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"FN har udr\u00e5bt d. 20 maj som biernes dag i et fors\u00f8g p\u00e5 at rette fokus p\u00e5 biernes vanskellige vilk\u00e5r, og deres store betydning.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bilauget-10.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bilauget-10.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/loerdag-d-20-maj-er-det-biernes-dag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f8rdag d. 20 maj er det biernes dag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samstag, der 1. 20. Mai ist Bienentag - Das Gr\u00fcne Museum","description":"Um auf die schwierige Lage der Bienen und ihre gro\u00dfe Bedeutung aufmerksam zu machen, hat die UNO den 20. Mai zum Tag der Biene erkl\u00e4rt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/samstag-20-mai-ist-bienentag\/","og_locale":"de_DE","og_type":"article","og_title":"L\u00f8rdag d. 20 maj er det biernes dag - Det Gr\u00f8nne Museum","og_description":"FN har udr\u00e5bt d. 20 maj som biernes dag i et fors\u00f8g p\u00e5 at rette fokus p\u00e5 biernes vanskellige vilk\u00e5r, og deres store betydning.","og_url":"https:\/\/detgroennemuseum.dk\/de\/samstag-20-mai-ist-bienentag\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2023-05-17T13:29:54+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/06\/bilauget-10.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"L\u00f8rdag d. 20 maj er det biernes dag","datePublished":"2023-05-17T13:29:54+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/"},"wordCount":613,"image":{"@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/06\/bilauget-10.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/","url":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/","name":"Samstag, der 1. 20. Mai ist Bienentag - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/06\/bilauget-10.jpg","datePublished":"2023-05-17T13:29:54+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"Um auf die schwierige Lage der Bienen und ihre gro\u00dfe Bedeutung aufmerksam zu machen, hat die UNO den 20. Mai zum Tag der Biene erkl\u00e4rt.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/06\/bilauget-10.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/06\/bilauget-10.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/loerdag-d-20-maj-er-det-biernes-dag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"L\u00f8rdag d. 20 maj er det biernes dag"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/22258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=22258"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/22258\/revisions"}],"predecessor-version":[{"id":22259,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/22258\/revisions\/22259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/11801"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=22258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=22258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=22258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}