{"id":21938,"date":"2023-02-21T10:52:48","date_gmt":"2023-02-21T09:52:48","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=21938"},"modified":"2023-03-01T11:42:48","modified_gmt":"2023-03-01T10:42:48","slug":"museumsgaste-saten-einen-wald-von-der-grose-zweier-fusballfelder","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/","title":{"rendered":"Museumsg\u00e4ste pflanzten einen Wald von der Gr\u00f6\u00dfe zweier Fu\u00dfballfelder"},"content":{"rendered":"<h3>Museumsg\u00e4ste pflanzten einen Wald von der Gr\u00f6\u00dfe zweier Fu\u00dfballfelder<\/h3>\n<div id=\"attachment_21939\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-21939\" class=\"wp-image-21939 size-medium lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947-600x400.jpg.webp\" alt=\"Zwei G\u00e4ste beim Auss\u00e4en von Baumsamen\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947-64x43.jpg.webp 64w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg.webp 1305w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-21939\" class=\"wp-caption-text\">Zwei G\u00e4ste s\u00e4en einige der \u00fcber 500 Baumsamen aus, die w\u00e4hrend der Winterferien ges\u00e4t wurden.<\/p><\/div>\n<p><strong>W\u00e4hrend der Winterferien nahmen viele gl\u00fcckliche G\u00e4ste jeden Alters an den zahlreichen kostenlosen Aktivit\u00e4ten im Gr\u00fcnen Museum teil und sorgten so f\u00fcr einen gelungenen Start in die Museumssaison 2023.<\/strong><\/p>\n<p>Mit dem Fokus auf den Wald und den Werkstoff Holz wurde in und rund um die stimmungsvolle Ausstellung des Museums ein gro\u00dfes Indoor-Walderlebnis geboten. <a href=\"https:\/\/detgroennemuseum.dk\/de\/gros\/\" target=\"_blank\" rel=\"noopener\">\u201eSTORT \u2013 Der Mensch und der Wald\u201c<\/a>.<\/p>\n<p>Die neueste Erg\u00e4nzung der Ausstellung, das Schlauchboot Afrodite, wurde sowohl untersucht als auch genossen, da viele begeisterte G\u00e4ste in das sch\u00f6ne Schlauchboot stiegen, das wir ausgeliehen haben von <a href=\"https:\/\/limfjordsmuseet.dk\/\" target=\"_blank\" rel=\"noopener\">Limfjordmuseum<\/a>.<\/p>\n<p>Dar\u00fcber hinaus wurde nat\u00fcrlich auch mit der Zweimanns\u00e4ge ges\u00e4gt, mit gro\u00dfen Holzkl\u00f6tzen gebaut, Waldquiz gel\u00f6st und vieles mehr rund um das Thema \u201eDer Mensch und der Wald\u201c geboten.<\/p>\n<p>Aber das wahrscheinlich Erfreulichste f\u00fcr das Museum war, dass \u00fcber 500 Besucher ihre eigenen Baumsamen im Museum auss\u00e4ten, die sie dann mit nach Hause nahmen, um sie zu pflegen und zu hegen und sie hoffentlich irgendwann zum Beispiel in ihrem eigenen Garten auszupflanzen.<\/p>\n<p>Bei 500 B\u00e4umen kann das ca. entsprechen. Zwei Fu\u00dfballfelder (ein Hektar) Wald, den die G\u00e4ste des Museums mitgepflanzt haben \u2013 wenn aus den kleinen Samen gro\u00dfe, kr\u00e4ftige und etwa 25 Meter hohe B\u00e4ume geworden sind.<\/p>\n<p>Denn wenn man sich die Zahlen ansieht, die das Forschungszentrum f\u00fcr Wald und Landschaft im Rahmen einiger seiner 400 langfristigen Waldversuche ver\u00f6ffentlicht hat, zeigt sich, dass durch die Anpflanzung von beispielsweise Gemeiner Fichte (einer der vier B\u00e4ume, die man in den Winterferien im Gr\u00fcnen Museum pflanzen konnte) ein Hektar Gemeiner Fichte, wo die B\u00e4ume ca. 25-30 Meter hoch, von ca. 400 B\u00e4ume (Quelle: <a href=\"https:\/\/www.skoven-i-skolen.dk\/content\/skovdyrkning\" target=\"_blank\" rel=\"noopener\">https:\/\/www.skoven-i-skolen.dk\/content\/skovdyrkning<\/a>).<\/p>\n<h4>Kostenlose Jahreskarte f\u00fcr zahlende G\u00e4ste<\/h4>\n<p>W\u00e4hrend der gesamten Winterferien gab es f\u00fcr Museumsbesucher ein kostenloses Upgrade der gekauften Tageskarte zur Jahreskarte. Ein Angebot, das die vielen G\u00e4ste, aber auch die Mitarbeiter des Museums erfreute, da es hoffentlich vielen Menschen die M\u00f6glichkeit gibt, das Museum zu besuchen und die vielen Ausstellungen im Innenbereich und nicht zuletzt im Au\u00dfenbereich zu erleben, wo der Wechsel der Jahreszeiten dazu beitr\u00e4gt, jeden Besuch zu etwas ganz Besonderem zu machen.<\/p>\n<p>\u201eIm Gr\u00fcnen Museum bieten wir eine F\u00fclle von Ausstellungen, Erlebnissen und Perspektiven. Unsere Ausstellungsfl\u00e4chen im Innen- und Au\u00dfenbereich umfassen 6.000 bzw. 60.000 m2, was etwa 10 Fu\u00dfballfeldern entspricht \u2013 weit mehr, als man an einem Tag erkunden kann. Mit dem kostenlosen Upgrade der Eintrittskarte auf eine Jahreskarte hoffen wir, dass mehr Menschen die M\u00f6glichkeit haben, wiederzukommen und das vielf\u00e4ltige Angebot des Museums das ganze Jahr \u00fcber zu erleben\u201c, sagt Anne Bjerrek\u00e6r, Direktorin des Gr\u00fcnen Museums.<\/p>\n<p>Sie haben noch immer die M\u00f6glichkeit, von diesem tollen Angebot zu profitieren, denn es ist den ganzen Februar \u00fcber g\u00fcltig. Falls Sie es in den Winterferien nicht geschafft haben, uns zu besuchen, ist das kostenlose Upgrade Ihrer gekauften Eintrittskarte ein guter Grund, im Februar bei uns vorbeizuschauen \u2013 und sich so den Zugang zu unseren vielen spannenden Aktionen und interessanten Ausstellungen f\u00fcr den Rest des Jahres zu sichern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Museumsg\u00e4ste pflanzten einen Wald von der Gr\u00f6\u00dfe zweier Fu\u00dfballfelder. In den Winterferien gab es viele gl\u00fcckliche G\u00e4ste jeden Alters, die an den vielen kostenlosen Aktivit\u00e4ten im\u2026 teilnahmen.<\/p>","protected":false},"author":17,"featured_media":21939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-21938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov<\/title>\n<meta name=\"description\" content=\"I l\u00f8bet af vinterferien s\u00e5ede museets g\u00e6ster over 500 tr\u00e6fr\u00f8, som p\u00e5 sigt kan blive til over 2 fodboldbaner skov.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/museumsgaste-saten-einen-wald-von-der-grose-zweier-fusballfelder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov\" \/>\n<meta property=\"og:description\" content=\"I l\u00f8bet af vinterferien s\u00e5ede museets g\u00e6ster over 500 tr\u00e6fr\u00f8, som p\u00e5 sigt kan blive til over 2 fodboldbaner skov.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/museumsgaste-saten-einen-wald-von-der-grose-zweier-fusballfelder\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T09:52:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T10:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1305\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov\",\"datePublished\":\"2023-02-21T09:52:48+00:00\",\"dateModified\":\"2023-03-01T10:42:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/\"},\"wordCount\":587,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/\",\"name\":\"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg\",\"datePublished\":\"2023-02-21T09:52:48+00:00\",\"dateModified\":\"2023-03-01T10:42:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"I l\u00f8bet af vinterferien s\u00e5ede museets g\u00e6ster over 500 tr\u00e6fr\u00f8, som p\u00e5 sigt kan blive til over 2 fodboldbaner skov.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg\",\"width\":1305,\"height\":870,\"caption\":\"To g\u00e6ster er igang med at s\u00e5 nogle af de 500+ tr\u00e6fr\u00f8, som blev s\u00e5et i l\u00f8bet af vinterferien.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museumsg\u00e4ste pflanzten einen Wald von der Gr\u00f6\u00dfe zweier Fu\u00dfballfelder","description":"W\u00e4hrend der Winterpause s\u00e4ten Museumsg\u00e4ste \u00fcber 500 Baumsamen aus, aus denen schlie\u00dflich mehr als zwei Fu\u00dfballfelder Wald heranwachsen k\u00f6nnten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/museumsgaste-saten-einen-wald-von-der-grose-zweier-fusballfelder\/","og_locale":"de_DE","og_type":"article","og_title":"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov","og_description":"I l\u00f8bet af vinterferien s\u00e5ede museets g\u00e6ster over 500 tr\u00e6fr\u00f8, som p\u00e5 sigt kan blive til over 2 fodboldbaner skov.","og_url":"https:\/\/detgroennemuseum.dk\/de\/museumsgaste-saten-einen-wald-von-der-grose-zweier-fusballfelder\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2023-02-21T09:52:48+00:00","article_modified_time":"2023-03-01T10:42:48+00:00","og_image":[{"width":1305,"height":870,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov","datePublished":"2023-02-21T09:52:48+00:00","dateModified":"2023-03-01T10:42:48+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/"},"wordCount":587,"image":{"@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/","url":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/","name":"Museumsg\u00e4ste pflanzten einen Wald von der Gr\u00f6\u00dfe zweier Fu\u00dfballfelder","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg","datePublished":"2023-02-21T09:52:48+00:00","dateModified":"2023-03-01T10:42:48+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"W\u00e4hrend der Winterpause s\u00e4ten Museumsg\u00e4ste \u00fcber 500 Baumsamen aus, aus denen schlie\u00dflich mehr als zwei Fu\u00dfballfelder Wald heranwachsen k\u00f6nnten.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Vinterferie-2023-til-SoMe-04-e1676973088947.jpg","width":1305,"height":870,"caption":"To g\u00e6ster er igang med at s\u00e5 nogle af de 500+ tr\u00e6fr\u00f8, som blev s\u00e5et i l\u00f8bet af vinterferien."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/museets-gaester-saaede-en-to-fodboldbaner-stor-skov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Museets g\u00e6ster s\u00e5ede en to fodboldbaner stor skov"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/21938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=21938"}],"version-history":[{"count":5,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/21938\/revisions"}],"predecessor-version":[{"id":22056,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/21938\/revisions\/22056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/21939"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=21938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=21938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=21938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}