{"id":21220,"date":"2023-02-01T10:51:05","date_gmt":"2023-02-01T09:51:05","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=21220"},"modified":"2023-03-03T09:08:20","modified_gmt":"2023-03-03T08:08:20","slug":"winterurlaub-mit-indoor-waldaktivitaten","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/vinterferie-med-indendoers-skovaktiviteter\/","title":{"rendered":"Winterurlaub mit Indoor-Waldaktivit\u00e4ten"},"content":{"rendered":"<h3>Winterurlaub mit Indoor-Waldaktivit\u00e4ten<\/h3>\n<div id=\"attachment_21221\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-21221\" class=\"size-medium wp-image-21221 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2-600x400.jpg.webp\" alt=\"Ein gro\u00dfer Erfolg sind die vielen lustigen Waldaktivit\u00e4ten, darunter nicht zuletzt die M\u00f6glichkeit, mit einer der gro\u00dfen Zweimanns\u00e4gen gro\u00dfe Holzst\u00fccke zu s\u00e4gen.\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2-64x43.jpg.webp 64w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg.webp 1500w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-21221\" class=\"wp-caption-text\">Ein gro\u00dfer Erfolg sind die vielen lustigen Waldaktivit\u00e4ten, darunter nicht zuletzt die M\u00f6glichkeit, mit einer der gro\u00dfen Zweimanns\u00e4gen gro\u00dfe Holzst\u00fccke zu s\u00e4gen.<\/p><\/div>\n<p><strong>In den Winterferien k\u00f6nnt ihr jede Menge spannende und lehrreiche Aktionen f\u00fcr die ganze Familie erleben, wenn wir euch ab dem 11. Februar zur Saisoner\u00f6ffnung 2023 in den 800 m2 gro\u00dfen Indoor-Wald einladen.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Der Wald und die einzelne Pflanze sind f\u00fcr uns Menschen eine unglaublich wichtige Ressource. Nicht nur im Zusammenhang mit der Photosynthese und der Sauerstoffbildung. Gleichzeitig ist Holz ein weit verbreitetes Material, das wir Menschen im Laufe der Geschichte f\u00fcr alles M\u00f6gliche verwendet haben, von kleinen Streichh\u00f6lzern bis hin zu riesigen Geb\u00e4uden und Schiffen.<\/p>\n<p>Doch wenn man mitten im Wald steht, kann es schwierig sein, den Wald vor lauter B\u00e4umen zu sehen \u2013 mit Wissen ist es gl\u00fccklicherweise genau andersherum. Denn wenn man mitten im Indoor-Wald des Gr\u00fcnen Museums und der Ausstellung \u201eSTORT \u2013 Mensch und Wald\u201c steht, kann man gar nicht anders, als all das Wissen zu sehen, das einen im Wald umgibt.<\/p>\n<h2><strong>Holen Sie sich Ihren eigenen Baum nach Hause<\/strong><\/h2>\n<p>In den Winterferien wimmelt es in den B\u00e4umen des Indoor-Waldes des Gr\u00fcnen Museums von spannenden Aktionen und Aktionen, die alle kostenlos sind, wenn der Eintritt f\u00fcr Erwachsene bezahlt wird (f\u00fcr Jugendliche unter 18 Jahren ist der Eintritt immer frei).<\/p>\n<p>Sie k\u00f6nnen beispielsweise Ihren eigenen Topf aus recycelten Materialien herstellen, einen Baumsamen s\u00e4en und ihn mit nach Hause nehmen, um ihn auf der Fensterbank wachsen zu sehen.<\/p>\n<p>Au\u00dferdem k\u00f6nnen Sie Ihr Wissen beim Winterferienquiz des Museums testen oder mit einem ganzen Kubikmeter Holz bauen.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Leben als Waldarbeiter<\/strong><\/h2>\n<p>F\u00fcr manche von uns ist der Wald ein Zufluchtsort und eine heilige Oase im hektischen Alltag mit Arbeit und Verpflichtungen. F\u00fcr andere wiederum ist der Wald nicht nur ein R\u00fcckzugsort, sondern auch ein Arbeitsplatz mit Verpflichtungen. Und jetzt k\u00f6nnen Sie einen kleinen Vorgeschmack darauf bekommen, was es bedeutet, ein Waldarbeiter zu sein. wenn Sie das Museum besuchen und den Indoor-Wald und die vielen Angebote erleben.<\/p>\n<p>Denn ganz im Stil des Forstwirts geht es hier mit der gro\u00dfen, altmodischen Zweimanns\u00e4ge ans S\u00e4gen; und vielleicht sogar als Waldarbeiter verkleidet \u2013 in echter Waldarbeiterkleidung. Au\u00dferdem k\u00f6nnen Sie sich in einem Kraftakt wie dem Holzheben versuchen, ganz im Stil der Forstwirtschaft und nach einer Anleitung aus dem Jahr 1909.<\/p>\n<p>Sie k\u00f6nnen auch lernen, die verschiedenen B\u00e4ume anhand von beispielsweise Bl\u00e4ttern oder \u00c4sten zu unterscheiden. aber auch das Z\u00e4hlen von Baumringen oder einfach nur stilles Sitzen in unserem Indoor-Wald und Entspannen beim Vogelgezwitscher und dem sanften Rascheln des Windes in den Bl\u00e4ttern; vielleicht w\u00e4hrend Sie \u00fcber das Leben meditieren. Oder m\u00f6chten Sie lieber ein wenig zeichnen und dar\u00fcber spekulieren, wie wir den Wald oder das Material Holz in Zukunft nutzen werden?<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Der neueste Zuwachs in der Ausstellung BIG<\/strong><\/h2>\n<p>Wenn das Museum zu den Winterferien \u00f6ffnet, wird die Ausstellung um eine GROSSE Erweiterung erweitert. Das Museum hat gerade ein Luchsboot namens Afrodite vom Limfjordmuseum ausgeliehen, das Sie bewundern und auch einmal ausprobieren k\u00f6nnen \u2013 und dabei dar\u00fcber nachdenken, wie das Leben als Fischer fr\u00fcher aussah.<\/p>\n<p>Das Museum \u00f6ffnet am 11. Februar um 10 Uhr und ist w\u00e4hrend der Winterferien t\u00e4glich bis 16 Uhr ge\u00f6ffnet \u2013 und denken Sie daran, dass die Eintrittskarte f\u00fcr das Gr\u00fcne Museum auch den Zugang zu unserem gro\u00dfartigen Nachbarmuseum, dem Herrenhausmuseum Gammel Estrup, erm\u00f6glicht.<\/p>","protected":false},"excerpt":{"rendered":"<p>Winterferien mit Indoor-Waldaktivit\u00e4ten Erleben Sie in den Winterferien jede Menge spannende und lehrreiche Aktivit\u00e4ten f\u00fcr die ganze Familie, wenn wir Sie zur Saisoner\u00f6ffnung 2023 in die W\u00e4lder einladen.<\/p>","protected":false},"author":17,"featured_media":21221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-21220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vinterferie med indend\u00f8rs skovaktiviteter - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"I vinterferien kan du opleve et v\u00e6ld af sp\u00e6ndende og l\u00e6rerige aktiviteter for hele familien i den indend\u00f8rs 800 m2 store skov.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/winterurlaub-mit-indoor-waldaktivitaten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinterferie med indend\u00f8rs skovaktiviteter - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"I vinterferien kan du opleve et v\u00e6ld af sp\u00e6ndende og l\u00e6rerige aktiviteter for hele familien i den indend\u00f8rs 800 m2 store skov.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/winterurlaub-mit-indoor-waldaktivitaten\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T09:51:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T08:08:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Vinterferie med indend\u00f8rs skovaktiviteter\",\"datePublished\":\"2023-02-01T09:51:05+00:00\",\"dateModified\":\"2023-03-03T08:08:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/\"},\"wordCount\":612,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/\",\"name\":\"Vinterferie med indend\u00f8rs skovaktiviteter - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg\",\"datePublished\":\"2023-02-01T09:51:05+00:00\",\"dateModified\":\"2023-03-03T08:08:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"I vinterferien kan du opleve et v\u00e6ld af sp\u00e6ndende og l\u00e6rerige aktiviteter for hele familien i den indend\u00f8rs 800 m2 store skov.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"De mange sjove skovaktiviteter er altid et hit, og herunder ikke mindst muligheden for at save i store stykker tr\u00e6 med en af de store tomandssave.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/vinterferie-med-indendoers-skovaktiviteter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinterferie med indend\u00f8rs skovaktiviteter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winterurlaub mit Indoor-Waldaktivit\u00e4ten - Das Gr\u00fcne Museum","description":"In den Winterferien k\u00f6nnen Sie im 800 m2 gro\u00dfen Indoor-Wald jede Menge spannende und lehrreiche Aktionen f\u00fcr die ganze Familie erleben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/winterurlaub-mit-indoor-waldaktivitaten\/","og_locale":"de_DE","og_type":"article","og_title":"Vinterferie med indend\u00f8rs skovaktiviteter - Det Gr\u00f8nne Museum","og_description":"I vinterferien kan du opleve et v\u00e6ld af sp\u00e6ndende og l\u00e6rerige aktiviteter for hele familien i den indend\u00f8rs 800 m2 store skov.","og_url":"https:\/\/detgroennemuseum.dk\/de\/winterurlaub-mit-indoor-waldaktivitaten\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2023-02-01T09:51:05+00:00","article_modified_time":"2023-03-03T08:08:20+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Vinterferie med indend\u00f8rs skovaktiviteter","datePublished":"2023-02-01T09:51:05+00:00","dateModified":"2023-03-03T08:08:20+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/"},"wordCount":612,"image":{"@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/","url":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/","name":"Winterurlaub mit Indoor-Waldaktivit\u00e4ten - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg","datePublished":"2023-02-01T09:51:05+00:00","dateModified":"2023-03-03T08:08:20+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"In den Winterferien k\u00f6nnen Sie im 800 m2 gro\u00dfen Indoor-Wald jede Menge spannende und lehrreiche Aktionen f\u00fcr die ganze Familie erleben.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2023\/02\/Til-hjemmeside-og-SoMe-PM-Vinterferie-23-2.jpg","width":1500,"height":1000,"caption":"De mange sjove skovaktiviteter er altid et hit, og herunder ikke mindst muligheden for at save i store stykker tr\u00e6 med en af de store tomandssave."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/vinterferie-med-indendoers-skovaktiviteter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Vinterferie med indend\u00f8rs skovaktiviteter"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/21220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=21220"}],"version-history":[{"count":5,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/21220\/revisions"}],"predecessor-version":[{"id":22073,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/21220\/revisions\/22073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/21221"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=21220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=21220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=21220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}