{"id":20161,"date":"2022-11-02T11:21:32","date_gmt":"2022-11-02T10:21:32","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=20161"},"modified":"2022-11-02T11:21:32","modified_gmt":"2022-11-02T10:21:32","slug":"live-samstag-5-november","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/levende-loerdag-d-5-november\/","title":{"rendered":"Live Samstag d. 5. November"},"content":{"rendered":"<h3>Live Samstag d. 5. November<\/h3>\n<div id=\"attachment_20164\" style=\"width: 510px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20164\" class=\"wp-image-20164 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/STORT-gaester-22-600x400.jpg.webp\" alt=\"Freiwilliger Helfer bei BIG\" width=\"500\" height=\"333\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/STORT-gaester-22-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/STORT-gaester-22-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/STORT-gaester-22-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/STORT-gaester-22-1536x1024.jpg.webp 1536w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/STORT-gaester-22-2048x1365.jpg.webp 2048w\" data-sizes=\"(max-width: 500px) 100vw, 500px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/333;\" \/><p id=\"caption-attachment-20164\" class=\"wp-caption-text\">Einer der ehrenamtlichen Mitarbeiter des Museums spricht \u00fcber die Maschinen und sein langes Leben als Waldarbeiter.<\/p><\/div>\n<p><strong>Es gibt reichlich Gelegenheit, einen wundervollen Tag im Green Museum zu verbringen und einige unserer vielen Freiwilligen f\u00fcr Live Saturday kennenzulernen. 5. November zwischen 11 und 15 Uhr, wo sie bereit sind, unsere G\u00e4ste zu begr\u00fc\u00dfen.<\/strong><\/p>\n<p>Und falls Sie unsere GROSSE Ausstellung nach der Wiederer\u00f6ffnung noch nicht erlebt haben, dann ist auch der Samstag der perfekte Tag f\u00fcr einen Museumsbesuch. Viele der Tagesaktivit\u00e4ten finden in unserem Indoor-\u201eWald\u201c statt.<\/p>\n<p>So besteht beispielsweise die M\u00f6glichkeit, auf einer ca. 15-min\u00fctige Einf\u00fchrung in die Ausstellung gemeinsam mit einem unserer kompetenten Vermittler um 11:30, 12:30 oder 13:30 Uhr, Treffpunkt im Museumsshop.<\/p>\n<p>Dar\u00fcber hinaus k\u00f6nnen Sie Axel J\u00f8rgensen treffen, der nach 35 Jahren in den W\u00e4ldern des Forstbezirks Fussing\u00f8 bereit ist, \u00fcber die Arbeit im Wald und viele seiner spannenden Erlebnisse und Erfahrungen nach einem langen Arbeitsleben zu sprechen.<\/p>\n<p>Au\u00dferdem k\u00f6nnen Sie in der historischen Werkstatt eine historische Zwiebelsuppe probieren. Dort bereiten unsere Ehrenamtlichen ein Rezept aus dem Jahr 1844 zu, das ebenfalls auf dem alten Holzofen zubereitet wird.<\/p>\n<p>Schlie\u00dflich gibt es auch innerhalb von STORT viele unterhaltsame und lehrreiche Aktivit\u00e4ten f\u00fcr junge Leute, wo die M\u00f6glichkeit besteht, Baumst\u00e4mme zu heben, zu zeichnen oder mit der Brosch\u00fcre \u201eJagdaktivit\u00e4ten\u201c zu arbeiten und zu lesen.<\/p>\n<div id=\"attachment_20162\" style=\"width: 510px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20162\" class=\"wp-image-20162 lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/IMG_0126-600x375.jpeg.webp\" alt=\"Einf\u00fchrung BIG\" width=\"500\" height=\"313\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/IMG_0126-600x375.jpeg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/IMG_0126-1024x640.jpeg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/IMG_0126-768x480.jpeg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/IMG_0126-1536x960.jpeg.webp 1536w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/11\/IMG_0126.jpeg.webp 1929w\" data-sizes=\"(max-width: 500px) 100vw, 500px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/313;\" \/><p id=\"caption-attachment-20162\" class=\"wp-caption-text\">Eine Kommunikatorin des Museums arbeitet an einer Einf\u00fchrung zur Ausstellung BIG.<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Live Samstag d. 5. November Es gibt reichlich Gelegenheit, einen wundervollen Tag im Green Museum zu verbringen und einige unserer vielen Freiwilligen kennenzulernen \u2026<\/p>","protected":false},"author":17,"featured_media":20164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-20161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Levende l\u00f8rdag d. 5. november - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Der er rig mulighed for at komme og f\u00e5 en sk\u00f8n dag p\u00e5 Det Gr\u00f8nne Museum og m\u00f8de nogle af vores mange frivillige til levende l\u00f8rdag d. 5 nov.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Levende l\u00f8rdag d. 5. november - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Der er rig mulighed for at komme og f\u00e5 en sk\u00f8n dag p\u00e5 Det Gr\u00f8nne Museum og m\u00f8de nogle af vores mange frivillige til levende l\u00f8rdag d. 5 nov.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/live-samstag-5-november\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-02T10:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/11\/STORT-gaester-22-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Levende l\u00f8rdag d. 5. november\",\"datePublished\":\"2022-11-02T10:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/\"},\"wordCount\":281,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/STORT-gaester-22-scaled.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/\",\"name\":\"Levende l\u00f8rdag d. 5. november - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/STORT-gaester-22-scaled.jpg\",\"datePublished\":\"2022-11-02T10:21:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"Der er rig mulighed for at komme og f\u00e5 en sk\u00f8n dag p\u00e5 Det Gr\u00f8nne Museum og m\u00f8de nogle af vores mange frivillige til levende l\u00f8rdag d. 5 nov.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/STORT-gaester-22-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/STORT-gaester-22-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"En af museets frivillige fort\u00e6ller om maskinerne og sit lange liv som skovarbejder.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/levende-loerdag-d-5-november\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Levende l\u00f8rdag d. 5. november\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Live Samstag, 5. November - Das Gr\u00fcne Museum","description":"Es gibt reichlich Gelegenheit, einen wundervollen Tag im Green Museum zu verbringen und einige unserer vielen Freiwilligen f\u00fcr Live Saturday kennenzulernen. 5. November","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Levende l\u00f8rdag d. 5. november - Det Gr\u00f8nne Museum","og_description":"Der er rig mulighed for at komme og f\u00e5 en sk\u00f8n dag p\u00e5 Det Gr\u00f8nne Museum og m\u00f8de nogle af vores mange frivillige til levende l\u00f8rdag d. 5 nov.","og_url":"https:\/\/detgroennemuseum.dk\/de\/live-samstag-5-november\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2022-11-02T10:21:32+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/11\/STORT-gaester-22-scaled.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Levende l\u00f8rdag d. 5. november","datePublished":"2022-11-02T10:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/"},"wordCount":281,"image":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/11\/STORT-gaester-22-scaled.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/","url":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/","name":"Live Samstag, 5. November - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/11\/STORT-gaester-22-scaled.jpg","datePublished":"2022-11-02T10:21:32+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"Es gibt reichlich Gelegenheit, einen wundervollen Tag im Green Museum zu verbringen und einige unserer vielen Freiwilligen f\u00fcr Live Saturday kennenzulernen. 5. November","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/11\/STORT-gaester-22-scaled.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/11\/STORT-gaester-22-scaled.jpg","width":2560,"height":1707,"caption":"En af museets frivillige fort\u00e6ller om maskinerne og sit lange liv som skovarbejder."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/levende-loerdag-d-5-november\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Levende l\u00f8rdag d. 5. november"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/20161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=20161"}],"version-history":[{"count":1,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/20161\/revisions"}],"predecessor-version":[{"id":20166,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/20161\/revisions\/20166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/20164"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=20161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=20161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=20161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}