{"id":20080,"date":"2022-10-24T13:19:50","date_gmt":"2022-10-24T11:19:50","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=20080"},"modified":"2022-10-26T11:22:18","modified_gmt":"2022-10-26T09:22:18","slug":"viele-familien-mit-kindern-in-den-herbstferien","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/masser-af-boernefamilier-i-efteraarsferien\/","title":{"rendered":"Viele Familien mit Kindern in den Herbstferien"},"content":{"rendered":"<h3>Viele Familien mit Kindern und Aktivit\u00e4ten in den Herbstferien!<\/h3>\n<div id=\"attachment_20082\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20082\" class=\"wp-image-20082 size-medium lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7-600x400.jpg.webp\" alt=\"Herbstferien 2022 - Bogenschie\u00dfen\" width=\"600\" height=\"400\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7-600x400.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7-1024x683.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7-768x512.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg.webp 1500w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><p id=\"caption-attachment-20082\" class=\"wp-caption-text\">In den Herbstferien findet in der Ausstellung STORT ein Bogenschie\u00dfen statt.<\/p><\/div>\n<p><strong>Die Herbstferien im Gr\u00fcnen Museum standen in der wiederer\u00f6ffneten Ausstellung BIG ganz im Zeichen der Jagd. Und gemessen an der Reaktion und Besucherzahl der G\u00e4ste waren die Aktivit\u00e4ten des Museums und die Ausstellung STORT in der Version 2.0 ein voller Erfolg.<\/strong><\/p>\n<p>Besonders bei den Familien mit Kindern war die Freude gro\u00df, dass sie die Indoor-Waldausstellung besuchen und dort mit dem Bogen schie\u00dfen und ihren eigenen Pfeil verzieren durften.<\/p>\n<p>Wenn Sie es auch versuchen wollten \u2013 aber nicht die Gelegenheit dazu hatten. Also verzweifeln Sie nicht!<\/p>\n<p>Die Gelegenheit ist wieder da. 6. November f\u00fcr \u201eDas Spiel des Jahres\u201c \u2013 dabei bildet BIG den Rahmen f\u00fcr das gro\u00dfe Jagd-Aktionspaket des Museums.<\/p>\n<p><a href=\"https:\/\/detgroennemuseum.dk\/de\/aarets-vildtret\/\">Lesen Sie hier mehr \u00fcber das Spiel des Jahres.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Viele Familien mit Kindern und Aktivit\u00e4ten in den Herbstferien! Die Herbstferien im Gr\u00fcnen Museum standen in der wiederer\u00f6ffneten Ausstellung BIG ganz im Zeichen der Jagd. Und aufgrund der Reaktion und Anwesenheit der G\u00e4ste war es \u2026<\/p>","protected":false},"author":17,"featured_media":20082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-20080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Masser af b\u00f8rnefamilier i efter\u00e5rsferien - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Efter\u00e5rsferien p\u00e5 Det Gr\u00f8nne Museum stod i jagtens tegn. Og baseret p\u00e5 g\u00e6sternes reaktion og fremm\u00f8de, s\u00e5 var det et k\u00e6mpehit.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masser af b\u00f8rnefamilier i efter\u00e5rsferien - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Efter\u00e5rsferien p\u00e5 Det Gr\u00f8nne Museum stod i jagtens tegn. Og baseret p\u00e5 g\u00e6sternes reaktion og fremm\u00f8de, s\u00e5 var det et k\u00e6mpehit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/viele-familien-mit-kindern-in-den-herbstferien\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T11:19:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T09:22:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Masser af b\u00f8rnefamilier i efter\u00e5rsferien\",\"datePublished\":\"2022-10-24T11:19:50+00:00\",\"dateModified\":\"2022-10-26T09:22:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/\"},\"wordCount\":149,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/\",\"name\":\"Masser af b\u00f8rnefamilier i efter\u00e5rsferien - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg\",\"datePublished\":\"2022-10-24T11:19:50+00:00\",\"dateModified\":\"2022-10-26T09:22:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"Efter\u00e5rsferien p\u00e5 Det Gr\u00f8nne Museum stod i jagtens tegn. Og baseret p\u00e5 g\u00e6sternes reaktion og fremm\u00f8de, s\u00e5 var det et k\u00e6mpehit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Der bliver skudt med bue i udstillingen STORT i efter\u00e5rsferien.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/masser-af-boernefamilier-i-efteraarsferien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masser af b\u00f8rnefamilier i efter\u00e5rsferien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viele Familien mit Kindern in den Herbstferien - Das Gr\u00fcne Museum","description":"Die Herbstferien im Gr\u00fcnen Museum standen ganz im Zeichen der Jagd. Und der Reaktion und Anwesenheit der G\u00e4ste nach zu urteilen, war es ein Riesenerfolg.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Masser af b\u00f8rnefamilier i efter\u00e5rsferien - Det Gr\u00f8nne Museum","og_description":"Efter\u00e5rsferien p\u00e5 Det Gr\u00f8nne Museum stod i jagtens tegn. Og baseret p\u00e5 g\u00e6sternes reaktion og fremm\u00f8de, s\u00e5 var det et k\u00e6mpehit.","og_url":"https:\/\/detgroennemuseum.dk\/de\/viele-familien-mit-kindern-in-den-herbstferien\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2022-10-24T11:19:50+00:00","article_modified_time":"2022-10-26T09:22:18+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Masser af b\u00f8rnefamilier i efter\u00e5rsferien","datePublished":"2022-10-24T11:19:50+00:00","dateModified":"2022-10-26T09:22:18+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/"},"wordCount":149,"image":{"@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/","url":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/","name":"Viele Familien mit Kindern in den Herbstferien - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg","datePublished":"2022-10-24T11:19:50+00:00","dateModified":"2022-10-26T09:22:18+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"Die Herbstferien im Gr\u00fcnen Museum standen ganz im Zeichen der Jagd. Und der Reaktion und Anwesenheit der G\u00e4ste nach zu urteilen, war es ein Riesenerfolg.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/10\/Efteraarsferie-2022-i-jagtens-tegn-7.jpg","width":1500,"height":1000,"caption":"Der bliver skudt med bue i udstillingen STORT i efter\u00e5rsferien."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/masser-af-boernefamilier-i-efteraarsferien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Masser af b\u00f8rnefamilier i efter\u00e5rsferien"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/20080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=20080"}],"version-history":[{"count":4,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/20080\/revisions"}],"predecessor-version":[{"id":20089,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/20080\/revisions\/20089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/20082"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=20080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=20080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=20080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}