{"id":19853,"date":"2022-08-31T09:27:07","date_gmt":"2022-08-31T07:27:07","guid":{"rendered":"https:\/\/detgroennemuseum.dk\/?p=19853"},"modified":"2023-03-03T09:14:37","modified_gmt":"2023-03-03T08:14:37","slug":"karen-blixen-hot-dogs-und-norddjurs","status":"publish","type":"post","link":"https:\/\/detgroennemuseum.dk\/de\/karen-blixen-hot-dogs-og-norddjurs\/","title":{"rendered":"Karen Blixen, Hot Dogs und Norddjurs"},"content":{"rendered":"<h3>Karen Blixen, Hot Dogs und Norddjurs<\/h3>\n<div id=\"attachment_19854\" style=\"width: 610px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-19854\" class=\"wp-image-19854 size-medium lazyload\" data-src=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/08\/IMG_1034-600x379.jpg.webp\" alt=\"Pierre Miehe-Renard ist bereit\" width=\"600\" height=\"379\" data-srcset=\"https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/08\/IMG_1034-600x379.jpg.webp 600w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/08\/IMG_1034-1024x646.jpg.webp 1024w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/08\/IMG_1034-768x485.jpg.webp 768w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/08\/IMG_1034-1536x969.jpg.webp 1536w, https:\/\/detgroennemuseum.dk\/wp-content\/smush-webp\/2022\/08\/IMG_1034-2048x1292.jpg.webp 2048w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/379;\" \/><p id=\"caption-attachment-19854\" class=\"wp-caption-text\">Pierre Miehe-Renard ist bereit, als Karen Blixen zusammen mit der Lebensmittelhistorikerin des Museums, Bettina Buhl, das Aarhus Food Festival zu \u00fcbernehmen.<\/p><\/div>\n<p><strong>Das Food Festival Aarhus findet vom 2. bis 4. September statt und in diesem Zusammenhang hat die Lebensmittelhistorikerin des Gr\u00fcnen Museums, Bettina Buhl, ein umfangreiches, aber \u00e4u\u00dferst spannendes Programm zum Thema Essen und Geschichte zusammengestellt.<\/strong><\/p>\n<p>Die drei Tage bieten zahlreiche spannende Aktionen und Vortr\u00e4ge aus der gro\u00dfen Kulinarikszene.<\/p>\n<p>Denn zus\u00e4tzlich zu einem Gastauftritt auf der B\u00fchne, wenn S\u00f8ren Gerriche spricht; sowie einen spannenden Vortrag \u00fcber die Arbeit als Foodhistoriker. Die beiden wirklich gro\u00dfen Events sind dann die d\u00e4nische Hot-Dog-Meisterschaft in Zusammenarbeit mit Gastronom Kim Thygesen vom Restaurant Den Gamle Stald sowie ein Theaterst\u00fcck zur Lebensmittelgeschichte in Zusammenarbeit mit dem Schauspieler Pierre Miehe-Renard, der Gemeinde Norddjurs und Den Gamle Stald.<\/p>\n<p><strong>Die Speisekammer von Karen Blixen und Norddjur<\/strong><\/p>\n<p>Freitag, der 1. Am 2. September beginnen die Feierlichkeiten mit dem Theaterst\u00fcck zur Geschichte des Essens. Darin spielt Pierre Miehe-Renard eine alternde Karen Blixen, die auf die sch\u00f6nen Sommer auf Schloss Katholm bei Grenaa zur\u00fcckblickt.<\/p>\n<p>Besonders in Erinnerung geblieben sind ihr die feinen Gerichte und Zutaten, die sie bei ihrem Besuch auf Schloss Katholm genie\u00dfen durfte.<\/p>\n<p>Und Pierre Miehe-Renard freut sich auf den Auftritt am Freitag.<\/p>\n<p>\u2013 Ich liebe Herausforderungen und habe fast nie Nein zu einem Projekt gesagt, solange es ernsthaft und positiv war und die Teilnahme Spa\u00df machte. Ich stehe seit meinem dritten Lebensjahr auf den schr\u00e4gen Brettern. Aber dies ist das erste Mal, dass ich die Gelegenheit habe, Karen Blixen zu spielen. Und ich habe mich wirklich in die Rolle und Pers\u00f6nlichkeit vertieft und genie\u00dfe es, etwas Neues und eine neue Rolle auszuprobieren. \u201eIch habe keinen Zweifel, dass es f\u00fcr uns alle am Freitag eine gute und positive Erfahrung sein wird\u201c, sagt ein l\u00e4chelnder und optimistischer Pierre Miehe-Renard.<\/p>\n<p>Die beiden auf der B\u00fchne erstellten Men\u00fcs bleiben der Geschichte absolut treu. Die Lebensmittelhistorikerin Bettina Buhl hat sich in der Lokalgeschichte umgesehen und die alten Speisekarten aus den Sommern 1895 und 1896 von Schloss Katholm gefunden \u2013 sowohl die Mittags- als auch die Abendkarte. Und um so authentisch wie m\u00f6glich zu sein, werden nur lokal produzierte Zutaten verwendet. genau wie es 1895 der Fall war.<\/p>\n<p>Die beiden Gerichte, die hier kreiert werden, sind auf den Tag genau 127 Jahre alt, denn es handelt sich um die beiden Gerichte, die am 2. September 1895 auf Schloss Katholm serviert wurden.<\/p>\n<p><strong>Hot-Dog-Meisterschaft<\/strong><\/p>\n<p>Am Sonntag wartet das zweite gro\u00dfe Prestigeprojekt \u2013 die Teilnahme an der d\u00e4nischen Hot Dog Meisterschaft.<\/p>\n<p>Hier beteiligen sich das Gr\u00fcne Museum und das Restaurant Den Gamle Stald mit einem besonders spannenden Hot Dog. N\u00e4mlich das, was D\u00e4nemarks \u00e4ltester Hot Dog gewesen sein k\u00f6nnte.<\/p>\n<p>Denn in enger Zusammenarbeit haben die Foodhistorikerin Bettina Buhl und Kim Rosengreen von Bag &amp; Co. und Kim Thygesen und K\u00fcchenchef Martin Steentoft vom Restaurant haben einen Hot Dog kreiert, der von den Rohstoffen und der Zubereitung her eine sehr spannende und hoffentlich leckere Vorstellung davon ist, wie ein \u201aHot Dog\u2018 zu Harald Blauzahns Zeiten ausgesehen haben k\u00f6nnte \u2013 wenn der \u201aHot Dog\u2018 damals erfunden worden w\u00e4re.<\/p>\n<p>\u2013 Was wir \u00fcber die Rohstoffe aus dieser Zeit wissen, ist, dass beispielsweise Brot mit wilder Hefe gebacken wurde, also machen wir das nat\u00fcrlich auch und haben uns entschieden, wilde Hefe aus dem Regal zu verwenden. Dar\u00fcber hinaus wurde Wildfleisch verwendet, weshalb unser Hot Dog selbstverst\u00e4ndlich auf Rothirschfleisch basiert. Schlie\u00dflich wurde auch ein ganz besonderes Bier kreiert, basierend auf den Funden aus der Wikingerfestung Fyrkat; Dort wird es unter anderem mit Salbei zubereitet, sagt Bettina Buhl vom Gr\u00fcnen Museum.<\/p>\n<p>Die M\u00f6glichkeit, mit alten Aromen und Kochmethoden zu spielen \u2013 aber in einer modernen Interpretation \u2013 ist etwas, das Kim Thygesen von Den Gamle Stald genie\u00dft.<\/p>\n<p>\u2013 Die M\u00f6glichkeit, an der d\u00e4nischen Hot-Dog-Meisterschaft teilzunehmen, ist an sich schon aufregend. Aber wenn wir gemeinsam mit dem Green Museum einen historischen Hotdog zubereiten und dabei mit alten Techniken und Men\u00fcgestaltungsmethoden experimentieren k\u00f6nnen, trifft das genau meinen Nerv f\u00fcr meine berufliche Neugier und meine Freude am Schaffen. Daher freue ich mich sehr darauf, der Jury diesen Hotdog zu pr\u00e4sentieren, erkl\u00e4rt Kim Thygesen.<\/p>\n<p>Sehr passend f\u00fcr diesen Hot Dog, der D\u00e4nemarks erster seiner Art sein soll, ist, dass er \u201eHarald Bluetooth im Sumpf\u201c genannt wurde.<\/p>","protected":false},"excerpt":{"rendered":"<p>Karen Blixen, Hot Dogs und Norddjurs Das Food Festival Aarhus findet vom 2. bis 4. September statt, und in diesem Zusammenhang hat die Lebensmittelhistorikerin des Gr\u00fcnen Museums, Bettina Buhl, ein umfangreiches \u2013 aber \u00e4u\u00dferst spannendes \u2013 Programm \u2026<\/p>","protected":false},"author":17,"featured_media":19854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-19853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nyheder","category-79","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karen Blixen, Hot Dogs og Norddjurs - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"2-4 september afholdes Food Festival Aarhus, og i den forbindelse har Det Gr\u00f8nne Museums madhistoriker Bettina Buhl et sp\u00e6ndende program.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/karen-blixen-hot-dogs-und-norddjurs\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karen Blixen, Hot Dogs og Norddjurs - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"2-4 september afholdes Food Festival Aarhus, og i den forbindelse har Det Gr\u00f8nne Museums madhistoriker Bettina Buhl et sp\u00e6ndende program.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/karen-blixen-hot-dogs-und-norddjurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T07:27:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T08:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/08\/IMG_1034-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rune Kronenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rune Kronenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/\"},\"author\":{\"name\":\"Rune Kronenberg\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"headline\":\"Karen Blixen, Hot Dogs og Norddjurs\",\"datePublished\":\"2022-08-31T07:27:07+00:00\",\"dateModified\":\"2023-03-03T08:14:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/\"},\"wordCount\":788,\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/IMG_1034-scaled.jpg\",\"articleSection\":[\"Nyheder\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/\",\"name\":\"Karen Blixen, Hot Dogs og Norddjurs - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/IMG_1034-scaled.jpg\",\"datePublished\":\"2022-08-31T07:27:07+00:00\",\"dateModified\":\"2023-03-03T08:14:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\"},\"description\":\"2-4 september afholdes Food Festival Aarhus, og i den forbindelse har Det Gr\u00f8nne Museums madhistoriker Bettina Buhl et sp\u00e6ndende program.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/IMG_1034-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/IMG_1034-scaled.jpg\",\"width\":2560,\"height\":1615,\"caption\":\"Pierre Miehe-Renard er klar til at indtage Aarhus Food Festival som KAren Blixen, sammen med museets madhistoriker, Bettina Buhl.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/karen-blixen-hot-dogs-og-norddjurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karen Blixen, Hot Dogs og Norddjurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#\\\/schema\\\/person\\\/fff4ba61783c9bb44ccae8b534de0a2d\",\"name\":\"Rune Kronenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g\",\"caption\":\"Rune Kronenberg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karen Blixen, Hot Dogs und Norddjurs - Das Gr\u00fcne Museum","description":"Das Food Festival Aarhus findet vom 2. bis 4. September statt und in diesem Zusammenhang hat die Lebensmittelhistorikerin des Gr\u00fcnen Museums, Bettina Buhl, ein spannendes Programm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/karen-blixen-hot-dogs-und-norddjurs\/","og_locale":"de_DE","og_type":"article","og_title":"Karen Blixen, Hot Dogs og Norddjurs - Det Gr\u00f8nne Museum","og_description":"2-4 september afholdes Food Festival Aarhus, og i den forbindelse har Det Gr\u00f8nne Museums madhistoriker Bettina Buhl et sp\u00e6ndende program.","og_url":"https:\/\/detgroennemuseum.dk\/de\/karen-blixen-hot-dogs-und-norddjurs\/","og_site_name":"Det Gr\u00f8nne Museum","article_published_time":"2022-08-31T07:27:07+00:00","article_modified_time":"2023-03-03T08:14:37+00:00","og_image":[{"width":2560,"height":1615,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/08\/IMG_1034-scaled.jpg","type":"image\/jpeg"}],"author":"Rune Kronenberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rune Kronenberg","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#article","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/"},"author":{"name":"Rune Kronenberg","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"headline":"Karen Blixen, Hot Dogs og Norddjurs","datePublished":"2022-08-31T07:27:07+00:00","dateModified":"2023-03-03T08:14:37+00:00","mainEntityOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/"},"wordCount":788,"image":{"@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/08\/IMG_1034-scaled.jpg","articleSection":["Nyheder"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/","url":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/","name":"Karen Blixen, Hot Dogs und Norddjurs - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/08\/IMG_1034-scaled.jpg","datePublished":"2022-08-31T07:27:07+00:00","dateModified":"2023-03-03T08:14:37+00:00","author":{"@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d"},"description":"Das Food Festival Aarhus findet vom 2. bis 4. September statt und in diesem Zusammenhang hat die Lebensmittelhistorikerin des Gr\u00fcnen Museums, Bettina Buhl, ein spannendes Programm.","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/08\/IMG_1034-scaled.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2022\/08\/IMG_1034-scaled.jpg","width":2560,"height":1615,"caption":"Pierre Miehe-Renard er klar til at indtage Aarhus Food Festival som KAren Blixen, sammen med museets madhistoriker, Bettina Buhl."},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/karen-blixen-hot-dogs-og-norddjurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Karen Blixen, Hot Dogs og Norddjurs"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/detgroennemuseum.dk\/#\/schema\/person\/fff4ba61783c9bb44ccae8b534de0a2d","name":"Rune Kronenberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee8df02bc21ecc8997e9ac283a53033596837ccefb618e4bccb67783c50de46?s=96&d=mm&r=g","caption":"Rune Kronenberg"}}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/19853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=19853"}],"version-history":[{"count":4,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/19853\/revisions"}],"predecessor-version":[{"id":22082,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/posts\/19853\/revisions\/22082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/19854"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=19853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/categories?post=19853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/tags?post=19853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}