{"id":799,"date":"2017-09-27T14:10:11","date_gmt":"2017-09-27T12:10:11","guid":{"rendered":"http:\/\/detgroennemuseum.dk\/?page_id=799"},"modified":"2026-03-27T09:23:28","modified_gmt":"2026-03-27T08:23:28","slug":"stellenangebote","status":"publish","type":"page","link":"https:\/\/detgroennemuseum.dk\/de\/forside\/ledige-stillinger\/","title":{"rendered":"Stellenangebote"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1639744875649\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h1 style=\"text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Stellenangebote<\/h1><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Im Green Museum ist derzeit eine Stelle vakant.<\/p>\n<p><a href=\"https:\/\/detgroennemuseum.dk\/de\/front\/stellenangebote\/zweijahriges-postdoc-stipendium-im-bereich-kulturgeschichte-der-landwirtschaft\/\" target=\"_blank\" rel=\"noopener\">Zweij\u00e4hriges Postdoktorat in der Kulturgeschichte der Landwirtschaft<\/a><\/p>\n<p>Initiativbewerbungen richten Sie bitte an: <span style=\"color: #98c218;\"><a style=\"color: #98c218;\" href=\"https:\/\/post.borger.dk\/?logon=borger&amp;function=inbox&amp;mailboxid=31607\">klicken Sie hier.<\/a><\/span><\/p>\n<p>\u00dcber den obigen Link gelangen Sie zu borger.dk, wo Sie aufgefordert werden, sich mit NemID anzumelden. Sobald Sie eingeloggt sind, haben Sie die M\u00f6glichkeit, uns eine E-Mail zu schreiben. Es ist wichtig, dass Sie den obigen Link zum Sichern von E-Mails verwenden, damit wir Ihre personenbezogenen Daten verantwortungsvoll verarbeiten k\u00f6nnen.<\/p>\n<p><strong>AUFMERKSAMKEIT!<\/strong><\/p>\n<p><strong>Borger.dk hat derzeit Probleme mit der Einrichtung. Dies bedeutet, dass manche Personen eine E-Mail mit uns als Empf\u00e4nger nicht \u00f6ffnen k\u00f6nnen. Leider liegt derzeit keine Zeitsch\u00e4tzung vor. Wenn Ihnen das passiert, gehen Sie bitte wie folgt vor.<\/strong><\/p>\n<p><strong>1: Dr\u00fccken Sie auf der linken Seite auf \u201eNeue Nachricht schreiben\u201c.<\/strong><\/p>\n<p><strong>2: Suchen Sie unter \u201eAutorit\u00e4t\u201c nach \u201eThe Green Museum\u201c.<\/strong><\/p>\n<p><strong>3: Dr\u00fccken Sie \u201eKategorie ausw\u00e4hlen\u201c und w\u00e4hlen Sie \u201eThe Green Museum \u2013 HR\u201c<\/strong><\/p>\n<p><strong>4: Verfassen Sie eine passende Betreffzeile, geben Sie Ihre Nachricht ein und h\u00e4ngen Sie relevante Dokumente an<\/strong><\/p>\n<p><strong>5: Denken Sie daran, zu senden.\u00a0<img decoding=\"async\" class=\"emoji lazyload\" role=\"img\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f642.svg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Stellenangebot: Im Green Museum ist derzeit eine zweij\u00e4hrige Postdoc-Stelle im Bereich Kulturgeschichte der Landwirtschaft zu besetzen. Initiativbewerbungen k\u00f6nnen Sie uns hier zusenden. Der obige Link sendet\u2026<\/p>","protected":false},"author":1,"featured_media":10251,"parent":421,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"class_list":["post-799","page","type-page","status-publish","has-post-thumbnail","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ledige stillinger - Det Gr\u00f8nne Museum<\/title>\n<meta name=\"description\" content=\"Se ledige stillinger p\u00e5 Det Gr\u00f8nne Museum. M\u00e5ske er der en mulighed til dig. Se mere her\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/detgroennemuseum.dk\/de\/front\/stellenangebote\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ledige stillinger - Det Gr\u00f8nne Museum\" \/>\n<meta property=\"og:description\" content=\"Se ledige stillinger p\u00e5 Det Gr\u00f8nne Museum. M\u00e5ske er der en mulighed til dig. Se mere her\" \/>\n<meta property=\"og:url\" content=\"https:\/\/detgroennemuseum.dk\/de\/front\/stellenangebote\/\" \/>\n<meta property=\"og:site_name\" content=\"Det Gr\u00f8nne Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T08:23:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/01\/indgangsparti-2-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/\",\"name\":\"Ledige stillinger - Det Gr\u00f8nne Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/indgangsparti-2-4.jpg\",\"datePublished\":\"2017-09-27T12:10:11+00:00\",\"dateModified\":\"2026-03-27T08:23:28+00:00\",\"description\":\"Se ledige stillinger p\u00e5 Det Gr\u00f8nne Museum. M\u00e5ske er der en mulighed til dig. Se mere her\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/indgangsparti-2-4.jpg\",\"contentUrl\":\"https:\\\/\\\/detgroennemuseum.dk\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/indgangsparti-2-4.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Se hvorn\u00e5r du kan komme p\u00e5 gammel estrup i det gr\u00f8nne museums \u00e5bningstider\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/forside\\\/ledige-stillinger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forside\",\"item\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ledige stillinger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/detgroennemuseum.dk\\\/#website\",\"url\":\"https:\\\/\\\/detgroennemuseum.dk\\\/\",\"name\":\"Det Gr\u00f8nne Museum\",\"description\":\"Danmarks nationale museum for jagten, skoven, landbruget og maden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/detgroennemuseum.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offene Stellen - Das Gr\u00fcne Museum","description":"Sehen Sie sich die verf\u00fcgbaren Stellen im Green Museum an. Vielleicht ist eine M\u00f6glichkeit f\u00fcr Sie dabei. Mehr dazu hier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/detgroennemuseum.dk\/de\/front\/stellenangebote\/","og_locale":"de_DE","og_type":"article","og_title":"Ledige stillinger - Det Gr\u00f8nne Museum","og_description":"Se ledige stillinger p\u00e5 Det Gr\u00f8nne Museum. M\u00e5ske er der en mulighed til dig. Se mere her","og_url":"https:\/\/detgroennemuseum.dk\/de\/front\/stellenangebote\/","og_site_name":"Det Gr\u00f8nne Museum","article_modified_time":"2026-03-27T08:23:28+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/01\/indgangsparti-2-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/","url":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/","name":"Offene Stellen - Das Gr\u00fcne Museum","isPartOf":{"@id":"https:\/\/detgroennemuseum.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/#primaryimage"},"image":{"@id":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/#primaryimage"},"thumbnailUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/01\/indgangsparti-2-4.jpg","datePublished":"2017-09-27T12:10:11+00:00","dateModified":"2026-03-27T08:23:28+00:00","description":"Sehen Sie sich die verf\u00fcgbaren Stellen im Green Museum an. Vielleicht ist eine M\u00f6glichkeit f\u00fcr Sie dabei. Mehr dazu hier","breadcrumb":{"@id":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/#primaryimage","url":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/01\/indgangsparti-2-4.jpg","contentUrl":"https:\/\/detgroennemuseum.dk\/wp-content\/uploads\/2020\/01\/indgangsparti-2-4.jpg","width":1920,"height":1280,"caption":"Se hvorn\u00e5r du kan komme p\u00e5 gammel estrup i det gr\u00f8nne museums \u00e5bningstider"},{"@type":"BreadcrumbList","@id":"https:\/\/detgroennemuseum.dk\/forside\/ledige-stillinger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":2,"name":"Forside","item":"https:\/\/detgroennemuseum.dk\/"},{"@type":"ListItem","position":3,"name":"Ledige stillinger"}]},{"@type":"WebSite","@id":"https:\/\/detgroennemuseum.dk\/#website","url":"https:\/\/detgroennemuseum.dk\/","name":"Das Gr\u00fcne Museum","description":"D\u00e4nisches Nationalmuseum f\u00fcr Jagd, Forstwirtschaft, Landwirtschaft und Ern\u00e4hrung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/detgroennemuseum.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/pages\/799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/comments?post=799"}],"version-history":[{"count":41,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/pages\/799\/revisions"}],"predecessor-version":[{"id":26836,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/pages\/799\/revisions\/26836"}],"up":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/pages\/421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media\/10251"}],"wp:attachment":[{"href":"https:\/\/detgroennemuseum.dk\/de\/wp-json\/wp\/v2\/media?parent=799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}